{"id":98591,"date":"2025-04-29T08:33:49","date_gmt":"2025-04-29T14:33:49","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=98591"},"modified":"2025-04-29T08:33:50","modified_gmt":"2025-04-29T14:33:50","slug":"el-enigmatico-mundo-bajo-nuestros-pies-unos-suelos-saludables-son-los-cimientos-para-un-planeta-saludable-el-mundo","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/el-enigmatico-mundo-bajo-nuestros-pies-unos-suelos-saludables-son-los-cimientos-para-un-planeta-saludable-el-mundo\/","title":{"rendered":"El enigm\u00e1tico mundo bajo nuestros pies: \u00abUnos suelos saludables son los cimientos para un planeta saludable\u00bb | El Mundo"},"content":{"rendered":"\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background has-medium-font-size\">Iniciativas como las de Toby Kiers, &#8216;la astronauta subterr\u00e1nea&#8217;, o las de Henrietta Courtauld y Bridget Elworthy, jardineras y &#8216;guardianas&#8217; de la tierra, intentan proteger y dar a conocer la importancia de los microorganisnos, bacterias y hongos del planeta: \u00abNuestra meta es hacer visible ese mundo oculto hasta ahora\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2025\/03\/21\/17425588143468.jpg\" alt=\"Cabeza de insecto fotografiada con microscopio electr\u00f3nico por France Bour\u00e9ly, la fot\u00f3grafa de lo invisible\"\/><figcaption class=\"wp-element-caption\">Cabeza de insecto fotografiada con microscopio electr\u00f3nico por France Bour\u00e9ly, la fot\u00f3grafa de lo invisible |  France Bour\u00e9ly<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.elmundo.es\/autor\/carlos-fresneda.html\"><\/a><\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-3a582aa974e8e243fc1fe0f28be265bc\"><strong><a href=\"https:\/\/www.elmundo.es\/autor\/carlos-fresneda.html\">Carlos Fresneda<\/a> \/ El Mundo<\/strong><\/p>\n\n\n\n<p>Londres<\/p>\n\n\n\n<p>Conocemos mejor la superficie de la Luna que el suelo que pisamos. En una cucharada de tierra hay m\u00e1s microorganismos vivos que humanos sobre la faz de la Tierra. Y los hongos act\u00faan de puente entre los dos mundos, conectando la biodiversidad de la superficie con<strong>&nbsp;redes subterr\u00e1neas<\/strong>&nbsp;que se propagan prodigiosamente como si fuera el internet de la naturaleza.<\/p>\n\n\n\n<p>\u00abBajo nuestros pies tiene lugar una danza extraordinaria y compleja que solo ahora estamos empezando a conocer y que tenemos que respetar\u00bb, advierten al un\u00edsono Henrietta Courtauld y Bridget Elworthy, m\u00e1s conocidas como<strong>&nbsp;The Land Gardeners,<\/strong>&nbsp;jardineras y al mismo tiempo \u00abguardianas\u00bb de la tierra.<\/p>\n\n\n\n<p>\u00ab<strong>Solo hemos mapeado hasta la fecha el 15% del microbioma\u00bb<\/strong>, recalca la singular pareja de activistas brit\u00e1nicas. \u00abLa ciencia sabe a\u00fan bastante poco del h\u00e1bitat m\u00e1s biodiverso del planeta y de su conexi\u00f3n con el resto de la vida. Los microoganisnos, las bacterias y los hongos son el sustento de todo lo que vemos en la superficie, empezando por las plantas\u00bb.<\/p>\n\n\n\n<p>Henrietta y Bridget est\u00e1n embarcadas ahora en la elaboraci\u00f3n de un mapa-mundi del activismo del subsuelo, con iniciativas que van de la planta de compost org\u00e1nico microbial de Els Sots en Centelles (Barcelona) a la granja de Chaos Springs en Nueva Zelanda, referencia mundial de agricultura biodin\u00e1mica y regenerativa.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2025\/03\/21\/17425739035348.jpg\" alt=\"Las jardineras Henrietta Courtauld y Bridget Elworthy, 'guardianas de la tierra'\"\/><figcaption class=\"wp-element-caption\">Las jardineras Henrietta Courtauld y Bridget Elworthy, &#8216;guardianas de la tierra&#8217;The Land Garderners<\/figcaption><\/figure>\n\n\n\n<p>\u00abUnos suelos saludables son los cimientos para un planeta saludable y una gente saludable\u00bb, sostienen The Land Gardeners. \u00abSe est\u00e1 creando por fin conciencia sobre esta relaci\u00f3n tan b\u00e1sica y estamos asistiendo a una reacci\u00f3n en cadena en todo el mundo, con proyectos fascinantes que est\u00e1n reivindicando la importancia de ese mundo que se extiende bajo nuestros pies\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8216;La astronauta subterr\u00e1nea&#8217;<\/h2>\n\n\n\n<p>A caballo entre el activismo y la ciencia se ha propagado en los \u00faltimos a\u00f1os la as\u00ed llamada<strong>&nbsp;Sociedad para la Protecci\u00f3n de las Redes Subterr\u00e1neas<\/strong>&nbsp;(SPUN). Su cofundadora Toby Kiers, de la Universidad Vrije de \u00c1msterdam, se ha ganado a pulso el sobrenombre de la \u00abastronauta\u00bb subterr\u00e1nea, por su empe\u00f1o en llegar m\u00e1s lejos que nadie y elaborar una base de datos mundial de diversidad micorr\u00edcica (la simbiosis entre hongos y ra\u00edces tan vital para las plantas).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2025\/03\/21\/17425739082212.jpg\" alt=\"Una muestra de tierra\"\/><figcaption class=\"wp-element-caption\">Una muestra de tierraThe Land Garderners<\/figcaption><\/figure>\n\n\n\n<p><strong>\u00abNuestra meta es hacer visible ese mundo oculto hasta ahora,<\/strong>&nbsp;de la misma manera que se hicieron visibles los fondos marinos o que pudimos ver la Tierra desde el espacio exterior\u00bb, explica la bi\u00f3loga holandesa. \u00abLas redes f\u00fangicas son como las barreras coralinas del subsuelo, que dan apoyo a una gran biodiversidad de organismos, al tiempo que secuestran carbono y act\u00faan como el \u00abpegamento\u00bb de los ecosistemas\u00bb.<\/p>\n\n\n\n<p><strong>\u00abLas actividades humanas est\u00e1n amenazando a esas redes a un ritmo muy r\u00e1pido,<\/strong>&nbsp;por eso es urgente identificarlas y cuantificarlas\u00bb, apunta Toby Kiers. \u00abSin ellas, corremos el riesgo de acelerar el cambio clim\u00e1tico y la p\u00e9rdida de biodiversidad, y provocar la interrupci\u00f3n del ciclo de los nutrientes\u00bb.<\/p>\n\n\n\n<p>De la Atacama a la Patagonia, de Utrecht a Lesotho, de Kazijist\u00e1n al atol\u00f3n d Palmyra, con seguimiento geoespacial y verificaciones sobre el terreno,&nbsp;<strong>los exploradores del subsuelo de SPUN aspiran a llegar a las 10.000 muestras en todos los continentes&nbsp;<\/strong>para elaborar la cartograf\u00eda de la biodiversidad micorr\u00edcica, calibrar las amenazas y reclamar su protecci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2025\/03\/21\/17425588124444.jpg\" alt=\"Una hormiga, vista al microscopio electr\u00f3nico\"\/><figcaption class=\"wp-element-caption\">Una hormiga, vista al microscopio electr\u00f3nicoFrance Bour\u00e9ly<\/figcaption><\/figure>\n\n\n\n<p>Desde las islas brit\u00e1nicas, entre tanto, las&nbsp;<em>land gardeners&nbsp;<\/em>Henrietta Courtauld y Bridget Elworthy se proponen por su parte crear una red mundial de iniciativas para velar por la riqueza org\u00e1nica de los suelos, frente a la invasi\u00f3n de pesticidas y fertilizantes qu\u00edmicos. En su reducto de Oxfordshire, y en su papel de horticultoras, ellas mismas se desmarcaron hace m\u00e1s de una d\u00e9cada explorando y propagando entre los agricultores locales los beneficios del compost&#8230;<\/p>\n\n\n\n<p><strong>\u00abSi nutrimos el suelo, el suelo nos nutrir\u00e1 a nosotros.&nbsp;<\/strong>Es todo lo que necesita la tierra: aire, agua y la m\u00ednima alteraci\u00f3n, para que los hongos y los microorganismos puedan llevar a cabo su m\u00e1gica relaci\u00f3n con las plantas. Y es tambi\u00e9n parte de la soluci\u00f3n al problema que tenemos: demasiado CO2 en la atm\u00f3sfera, demasiado poco CO2 en nuestros suelos\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exposici\u00f3n en Londres<\/h2>\n\n\n\n<p>Con un pasi\u00f3n contagiosa por todo que hacen, The Land Gardeners se han convertido en el alma de la exposici\u00f3n&nbsp;<em>Soil, the world at our feet&nbsp;<\/em>con la que la Somerset House de Londres celebra su 25 aniversario. Arte y activismo se dan la mano a lo largo de este ins\u00f3lito viaje en el que medio centenar de \u00abartivistas\u00bb nos invitan a reimaginar el suelo palpitante bajo nuestras suelas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2025\/03\/21\/17425602918036.jpg\" alt=\"Imagen de la exposici\u00f3n en Londres 'Suelo, el mundo bajo nuestros pies'\"\/><figcaption class=\"wp-element-caption\">Imagen de la exposici\u00f3n en Londres &#8216;Suelo, el mundo bajo nuestros pies&#8217;David Parry<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.elmundo.es\/espana\/2025\/04\/29\/6810b5a4fc6c831e478b4577.html\"><\/a><a href=\"https:\/\/www.elmundo.es\/espana\/2025\/04\/28\/680f931ce85ece86628b4598-video.html\"><\/a><\/p>\n\n\n\n<p>Los hongos de arcilla de Jo Pearl, la biblioteca de la tierra de Kim Mortonm o los micropaisajes subterr\u00e1neos ded Win van Egmond trazan la senda hasta&nbsp;<em>Poetics of Soil<\/em>, la experiencia de inmersi\u00f3n total y casi on\u00edrica en el submundo de los hongos, por gentileza de Marshmallow Laser Feast y con la voz del mic\u00f3logo Merlin Sheldrake poniendo el contrapunto cient\u00edfico.<\/p>\n\n\n\n<p><strong>\u00abDurante cientos de millones de a\u00f1os, los hongos han jugado un papel esencial como los grandes recicladores de la naturaleza,<\/strong>&nbsp;descomponiendo las plantas y animales muertos en mol\u00e9culas que vuelven a la tierra y fabricando nutrientes para alimentar los bosques. Esta simbiosis entre las plantas y los hongos forman tejidos en el subsuelo que funcionan como aut\u00e9nticas redes vivas, con una complejidad comparable a la del cerebro humano\u00bb.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.elmundo.es\/ciencia-y-salud\/ciencia\/2025\/04\/25\/67dd5640e9cf4ad1208b45a4.html\">https:\/\/www.elmundo.es\/ciencia-y-salud\/ciencia\/2025\/04\/25\/67dd5640e9cf4ad1208b45a4.html<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciativas como las de Toby Kiers, &#8216;la astronauta subterr\u00e1nea&#8217;, o las de Henrietta Courtauld y Bridget Elworthy, jardineras y &#8216;guardianas&#8217; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[37912,37910,37911],"class_list":["post-98591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-microbioma","tag-microorganismos","tag-the-land-gardeners"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/98591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=98591"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/98591\/revisions"}],"predecessor-version":[{"id":98593,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/98591\/revisions\/98593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/98592"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=98591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=98591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=98591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}