{"id":85426,"date":"2024-09-17T05:51:35","date_gmt":"2024-09-17T10:51:35","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=85426"},"modified":"2024-09-17T05:51:38","modified_gmt":"2024-09-17T10:51:38","slug":"cuando-la-catedral-resguardo-los-restos-de-7-heroes-de-la-independencia-dlf","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/cuando-la-catedral-resguardo-los-restos-de-7-heroes-de-la-independencia-dlf\/","title":{"rendered":"Cuando la Catedral resguard\u00f3 los restos de 7 h\u00e9roes de la Independencia | DLF"},"content":{"rendered":"\n<p class=\"has-light-green-cyan-background-color has-background has-medium-font-size\"><strong>El 17 de septiembre de 1823 los restos de 7 h\u00e9roes de la Independencia fueron llevados a la Catedral de M\u00e9xico; el Arz. Pedro Jos\u00e9 de Fonte los recibi\u00f3.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"699\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/iturbide-catedral-de-mexico.jpg-1024x699.webp\" alt=\"\" class=\"wp-image-85427\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/iturbide-catedral-de-mexico.jpg-1024x699.webp 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/iturbide-catedral-de-mexico.jpg-300x205.webp 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/iturbide-catedral-de-mexico.jpg-768x524.webp 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/iturbide-catedral-de-mexico.jpg.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Restos de Agust\u00edn de Iturbide en la Capilla de San Felipe de Jes\u00fas<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-9bd6995e69f63df4c4e49c52058317ce\"><strong>Por\u00a0\u00a0<a href=\"https:\/\/desdelafe.mx\/author\/mariadelsocorro\/\">Mar\u00eda del Socorro Sent\u00edes<\/a> \/ Desde la Fe<\/strong><\/p>\n\n\n\n<p>\u00bfSab\u00edas que en nuestra querida y hermosa Catedral de M\u00e9xico estuvieron los restos mortales de siete h\u00e9roes de nuestra Independencia? Los del libertador hasta actualidad se siguen conservando.<\/p>\n\n\n\n<p>El 19 de julio de 1823 se decret\u00f3 benem\u00e9ritos de la patria en grado heroico a 13 h\u00e9roes, y por ese motivo se dispuso que se exhumaran los restos, pero como estos personajes fueron fusilados en diferentes lugares del pa\u00eds, no fue posible reunir a todos, \u00fanicamente se pudieron rescatar en ese momento a siete, ellos son:&nbsp;<strong>Miguel Hidalgo, Ignacio Allende, Jos\u00e9 Mar\u00eda Morelos, Juan Aldama, Mariano Jim\u00e9nez, Francisco Javier Mina y Mariano Matamoros.<\/strong><\/p>\n\n\n\n<p>El 17 de septiembre de ese a\u00f1o fueron llevados a la Catedral Metropolitana, donde sus restos descansar\u00edan en paz, celebr\u00e1ndose el oficio de difuntos. A las 12 del d\u00eda lleg\u00f3 la procesi\u00f3n; el<strong>&nbsp;arzobispo Pedro Jos\u00e9 de Fonte<\/strong>&nbsp;autoriz\u00f3 que se abriera la puerta central de la Catedral. Esta puerta nunca se abre, solamente cuando entra un nuevo arzobispo a tomar posesi\u00f3n de su sede; despu\u00e9s de muerto cuando entra nuevamente para ser sepultado en la Cripta de los Arzobispos o en ocasiones muy especiales.<\/p>\n\n\n\n<p><strong>Los restos fueron conducidos en urnas y se colocaron al pie del Altar de los Reyes<\/strong>, disparando salvas militares y repitiendo la salva a la elevaci\u00f3n de la Hostia. El presidente del Congreso dijo:&nbsp;<em>\u201cLos huesos quedaron por ahora, sepultados en la b\u00f3veda de los Virreyes, bajo el Altar de los Santos Reyes de la Iglesia Catedral, hasta que la naci\u00f3n les erija el pante\u00f3n de que son digno\u201d.<\/em><\/p>\n\n\n\n<p>En 1894 los restos fueron sacados de la cripta y llevados a la capilla de San Jos\u00e9 en la misma Catedral, en una procesi\u00f3n liderada por el presidente&nbsp;<strong>Porfirio D\u00edaz<\/strong>; ah\u00ed permanecieron hasta 1925, cuando<strong>&nbsp;Plutarco El\u00edas Calles los traslad\u00f3 a la Columna de la Independencia<\/strong>.<\/p>\n\n\n\n<p>En el a\u00f1o de 1838, durante la administraci\u00f3n del presidente&nbsp;<strong>Anastasio Bustamante<\/strong>, se llev\u00f3 a cabo el rescate de los&nbsp;<strong>restos de Agust\u00edn de Iturbide<\/strong>, consumador de la Independencia. Los restos se trasladaron desde Padilla Tamaulipas a la Ciudad de M\u00e9xico, para ser recibidos en la Catedral; se celebraron exequias, y la urna fue depositada en la&nbsp;<strong>Capilla de San Felipe de Jes\u00fas<\/strong>, primer santo mexicano; donde tambi\u00e9n reposar\u00edan los restos del primer gobernante del M\u00e9xico independiente, junto al coraz\u00f3n de su fiel amigo el general Bustamante, lugar donde permanecen hasta la actualidad.<\/p>\n\n\n\n<p>\u00bfTe gustar\u00eda conocer la capilla y ver la urna que guardan los restos?<\/p>\n\n\n\n<p><em>La autora es Gu\u00eda de la Catedral Metropolitana.&nbsp;<\/em><\/p>\n\n\n\n<p>(Texto original publicado el 23 septiembre, 2020)<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/desdelafe.mx\/noticias\/sabias-que\/cuando-la-catedral-resguardo-los-restos-de-7-heroes-de-la-independencia\/\">https:\/\/desdelafe.mx\/noticias\/sabias-que\/cuando-la-catedral-resguardo-los-restos-de-7-heroes-de-la-independencia\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 17 de septiembre de 1823 los restos de 7 h\u00e9roes de la Independencia fueron llevados a la Catedral de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[30239,30241,30242],"class_list":["post-85426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-catedral-de-mexico","tag-heroes-de-la-independencia","tag-restos-7-heroes-independencia-mexico"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/85426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=85426"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/85426\/revisions"}],"predecessor-version":[{"id":85428,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/85426\/revisions\/85428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/85427"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=85426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=85426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=85426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}