{"id":85371,"date":"2024-09-16T12:22:09","date_gmt":"2024-09-16T17:22:09","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=85371"},"modified":"2024-09-16T12:22:11","modified_gmt":"2024-09-16T17:22:11","slug":"las-granjas-lecheras-de-estados-unidos-estan-desapareciendo-un-95-menos-que-en-los-anos-1970-las-normas-sobre-los-precios-de-la-leche-son-una-de-las-razones-the-conversation","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/las-granjas-lecheras-de-estados-unidos-estan-desapareciendo-un-95-menos-que-en-los-anos-1970-las-normas-sobre-los-precios-de-la-leche-son-una-de-las-razones-the-conversation\/","title":{"rendered":"Las granjas lecheras de Estados Unidos est\u00e1n desapareciendo, un 95% menos que en los a\u00f1os 1970: las normas sobre los precios de la leche son una de las razones | The Conversation"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"504\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/lecheras-1024x504.jpg\" alt=\"\" class=\"wp-image-85372\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/lecheras-1024x504.jpg 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/lecheras-300x148.jpg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/lecheras-768x378.jpg 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2024\/09\/lecheras.jpg 1356w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Administrar una granja lechera no es f\u00e1cil, especialmente cuando los costos de producci\u00f3n aumentan m\u00e1s r\u00e1pido que los ingresos.\u00a0 <a href=\"https:\/\/newsroom.ap.org\/detail\/LivestockHeatStress\/1a30a5f6a7824e669e9079d61a22d2d0\/photo\">AP Photo\/Charlie Neibergall<\/a><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-5e17b10209cf3461f84cace0432aef4b\"><strong><a href=\"https:\/\/theconversation.com\/profiles\/elizabeth-eckelkamp-1539819\">Elizabeth Eckelkamp<\/a> \/ The Conversation<\/strong><\/p>\n\n\n\n<p>Profesor asociado de ciencia animal y especialista en extensi\u00f3n lechera, Universidad de Tennessee<\/p>\n\n\n\n<p>Septiembre 16 2024<\/p>\n\n\n\n<p>Milton Orr mir\u00f3 las ondulantes colinas del noreste de Tennessee. \u201cRecuerdo cuando ten\u00edamos m\u00e1s de 1.000 granjas lecheras en este condado. Ahora tenemos menos de 40\u201d, me dijo Orr, asesor agr\u00edcola del condado de Greene, Tennessee, con un dejo de tristeza.<\/p>\n\n\n\n<p>Eso fue hace seis a\u00f1os. Hoy, solo quedan 14 granjas lecheras en el condado de Greene, y solo hay 125 granjas lecheras en todo Tennessee. En todo el pa\u00eds, la industria lechera est\u00e1 experimentando la misma tendencia: en 1970, m\u00e1s de&nbsp;<a href=\"https:\/\/www.ers.usda.gov\/webdocs\/publications\/45868\/17034_err47b_1_.pdf\">648.000 granjas lecheras estadounidenses orde\u00f1aban ganado<\/a>&nbsp;. Para 2022,&nbsp;<a href=\"https:\/\/www.nass.usda.gov\/Publications\/AgCensus\/2022\/Full_Report\/Volume_1,_Chapter_1_US\/usv1.pdf\">solo 24.470 granjas lecheras<\/a>&nbsp;estaban en funcionamiento.<\/p>\n\n\n\n<p>Si bien el n\u00famero de granjas lecheras ha disminuido, el tama\u00f1o promedio de los reba\u00f1os (la cantidad de vacas por granja) ha aumentado. Hoy,&nbsp;<a href=\"https:\/\/www.nass.usda.gov\/Publications\/AgCensus\/2022\/Full_Report\/Volume_1,_Chapter_1_US\/usv1.pdf\">m\u00e1s del 60%<\/a>&nbsp;de toda la producci\u00f3n de leche se produce en granjas con m\u00e1s de 2500 vacas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.theconversation.com\/files\/615398\/original\/file-20240823-19-azga3e.JPG?ixlib=rb-4.1.0&amp;q=45&amp;auto=format&amp;w=754&amp;fit=clip\" alt=\"Un gr\u00e1fico muestra que el n\u00famero de granjas ha disminuido desde la d\u00e9cada de 1970 y que el n\u00famero de vacas por granja ha aumentado en sentido inverso.\"\/><figcaption class=\"wp-element-caption\">El n\u00famero de granjas lecheras ha disminuido en las \u00faltimas d\u00e9cadas, pero las granjas m\u00e1s grandes han mantenido el n\u00famero total de vacas bastante estable.&nbsp;<a href=\"https:\/\/www.ers.usda.gov\/webdocs\/publications\/45868\/17034_err47b_1_.pdf\">USDA<\/a><\/figcaption><\/figure>\n\n\n\n<p>Esta concentraci\u00f3n masiva de la producci\u00f3n lechera tiene un impacto en las comunidades rurales. Tambi\u00e9n hace que a los consumidores les resulte m\u00e1s dif\u00edcil saber de d\u00f3nde provienen sus alimentos y c\u00f3mo se producen.<\/p>\n\n\n\n<p>Como&nbsp;<a href=\"https:\/\/faculty.utk.edu\/Elizabeth.Eckelkamp\/publications\">especialista en productos l\u00e1cteos<\/a>&nbsp;de la Universidad de Tennessee, me preguntan constantemente: \u00bfpor qu\u00e9 las lecher\u00edas est\u00e1n cerrando? Bueno, al igual que el estado civil de nuestros amigos en Facebook, es complicado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El problema con los precios<\/h2>\n\n\n\n<p>La mayor complicaci\u00f3n es c\u00f3mo se les paga a los productores lecheros por los productos que producen.<\/p>\n\n\n\n<p>En 1937, se establecieron las \u00d3rdenes Federales de Comercializaci\u00f3n de la Leche (FMMO, por sus siglas en ingl\u00e9s) en virtud de la&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/resources\/marketing-order-statistics\">Ley de Acuerdos de Comercializaci\u00f3n Agr\u00edcola<\/a>&nbsp;. El prop\u00f3sito de estas \u00f3rdenes era fijar un precio m\u00ednimo mensual uniforme para la leche en funci\u00f3n de su uso final y garantizar que los granjeros recibieran el pago de manera precisa y oportuna.<\/p>\n\n\n\n<p>A los agricultores se les pagaba en funci\u00f3n&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/sites\/default\/files\/media\/DairyFMMOBooklet.pdf\">del uso que se daba a la leche que cosechaban<\/a>&nbsp;, y as\u00ed sigue funcionando hoy en d\u00eda.<\/p>\n\n\n\n<p>\u00bfSe convierte en leche embotellada? Ese es&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/sites\/default\/files\/media\/ClassIworksheetfinal.pdf\">el precio de la Clase 1. \u00bf<\/a>&nbsp;Yogur?&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/sites\/default\/files\/media\/ClassIIworksheetfinal.pdf\">Precio de la Clase 2.<\/a>&nbsp;\u00bfQueso cheddar?&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/sites\/default\/files\/media\/ClassIIIworksheetfinal.pdf\">Precio de la Clase 3.<\/a>&nbsp;\u00bfMantequilla o leche en polvo?&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/sites\/default\/files\/media\/ClassIVworksheetfinal.pdf\">Clase 4.<\/a>&nbsp;Tradicionalmente, la Clase 1 recibe el precio m\u00e1s alto.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.theconversation.com\/files\/617936\/original\/file-20240906-16-b3088b.jpg?ixlib=rb-4.1.0&amp;q=45&amp;auto=format&amp;w=754&amp;fit=clip\" alt=\"Una mujer joven en una tienda abre la puerta de un refrigerador lleno de productos l\u00e1cteos.\"\/><figcaption class=\"wp-element-caption\">\u00bfSabes de d\u00f3nde viene la leche que consumes?&nbsp;<a href=\"https:\/\/newsroom.ap.org\/detail\/DeanFoodsSale\/4d12dd8ac3864a0bbe5d7e1423c7bb7d\/photo\">AP Photo\/Sue Ogrocki<\/a><\/figcaption><\/figure>\n\n\n\n<p>Hay 11 FMMO que dividen el pa\u00eds. Las FMMO de Florida, el sudeste y los Apalaches se concentran principalmente en la leche de clase 1, o embotellada. Las otras FMMO, como las del Alto Medio Oeste y el Noroeste del Pac\u00edfico, tienen m\u00e1s productos manufacturados, como queso y mantequilla.<\/p>\n\n\n\n<p>Durante las \u00faltimas d\u00e9cadas, los agricultores generalmente han recibido el precio m\u00ednimo. Las mejoras en la calidad de la leche, la producci\u00f3n, el transporte, la refrigeraci\u00f3n y el procesamiento de la misma dieron como resultado mayores cantidades de leche, una mayor vida \u00fatil y un mayor acceso a los productos en todo Estados Unidos. El aumento de la oferta redujo la competencia entre las plantas procesadoras y redujo los precios generales.<\/p>\n\n\n\n<p>Junto con estas mejoras en la producci\u00f3n vinieron&nbsp;<a href=\"https:\/\/www.nass.usda.gov\/Publications\/Highlights\/2024\/Census22_HL_Dairy.pdf\">mayores costos de producci\u00f3n<\/a>&nbsp;, como la alimentaci\u00f3n del ganado, la mano de obra agr\u00edcola, la atenci\u00f3n veterinaria y los costos de combustible y equipo.<\/p>\n\n\n\n<p>En 2022, investigadores de la Universidad de Tennessee&nbsp;<a href=\"https:\/\/www.adsa.org\/Portals\/0\/SiteContent\/Docs\/Meetings\/2022ADSA\/Abstracts_BOOK_2022.pdf?v=20220613\">compararon el precio<\/a>&nbsp;que se recibe por la leche en las distintas regiones&nbsp;<a href=\"https:\/\/utdairy.tennessee.edu\/wp-content\/uploads\/sites\/104\/2024\/09\/SADDairyResearchPresentation_Jones-2022.pdf\">con los costos primarios de producci\u00f3n<\/a>&nbsp;: alimentaci\u00f3n y mano de obra. Los resultados muestran por qu\u00e9 las granjas est\u00e1n en dificultades.<\/p>\n\n\n\n<p>De 2005 a 2020, los ingresos por ventas de leche por cada 100 libras de leche producidas oscilaron entre $11,54 y $29,80, con un precio promedio de $18,57. Durante ese mismo per\u00edodo, los costos totales para producir 100 libras de leche oscilaron entre $11,27 y $43,88, con un costo promedio de $25,80.<\/p>\n\n\n\n<p>En promedio, eso significaba que una sola vaca que produc\u00eda 24.000 libras de leche generaba unos 4.457 d\u00f3lares, pero producir esa leche costaba 6.192 d\u00f3lares, lo que significaba una p\u00e9rdida para el productor lechero.<\/p>\n\n\n\n<p>Las granjas m\u00e1s eficientes pueden reducir sus costos de producci\u00f3n al mejorar la salud de las vacas, el rendimiento reproductivo y&nbsp;<a href=\"https:\/\/www.agproud.com\/articles\/27254-calculating-feed-efficiency\">las tasas de conversi\u00f3n de alimento a leche<\/a>&nbsp;. Las granjas m\u00e1s grandes o los grupos de agricultores (cooperativas como Dairy Farmers of America) tambi\u00e9n pueden aprovechar la contrataci\u00f3n a futuro de granos y precios futuros de la leche. Las inversiones en tecnolog\u00edas de precisi\u00f3n, como sistemas de orde\u00f1o rob\u00f3tico, salas rotativas y tecnolog\u00edas reproductivas y sanitarias port\u00e1tiles, pueden ayudar a reducir los costos laborales en todas las granjas.https:\/\/datawrapper.dwcdn.net\/ET41X\/1\/<\/p>\n\n\n\n<p>Independientemente del tama\u00f1o, sobrevivir en la industria l\u00e1ctea requiere pasi\u00f3n, dedicaci\u00f3n y una gesti\u00f3n empresarial cuidadosa.<\/p>\n\n\n\n<p>Algunas regiones han sufrido mayores p\u00e9rdidas que otras, lo que se debe en gran medida a la forma en que se les paga a los agricultores, es decir, a las clases de leche y a los crecientes costos de producci\u00f3n en su zona. Existen&nbsp;<a href=\"https:\/\/www.rma.usda.gov\/\">algunos programas de seguros y cobertura<\/a>&nbsp;que pueden ayudar a los agricultores a compensar los altos costos de producci\u00f3n o las ca\u00eddas inesperadas de los precios. Si los agricultores los aprovechan, los datos muestran que pueden&nbsp;<a href=\"https:\/\/trace.tennessee.edu\/utk_gradthes\/11383\">funcionar como una red de seguridad<\/a>&nbsp;, pero no solucionan el problema subyacente de que los costos superan los ingresos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pasando la antorcha a los futuros agricultores<\/h2>\n\n\n\n<p>\u00bfPor qu\u00e9 algunos productores lecheros siguen persistiendo, a pesar de los bajos precios de la leche y los altos costos de producci\u00f3n?<\/p>\n\n\n\n<p>Para muchos productores, la respuesta es que se trata de un negocio familiar y forma parte de su herencia. El noventa y siete por ciento de las granjas lecheras de Estados Unidos son de propiedad y gesti\u00f3n familiar.<\/p>\n\n\n\n<p>Algunos han&nbsp;<a href=\"https:\/\/www.mccartyfamilyfarms.com\/\">crecido para sobrevivir<\/a>&nbsp;. Para muchos otros, la transici\u00f3n a la siguiente generaci\u00f3n es un gran obst\u00e1culo.<\/p>\n\n\n\n<p>La edad promedio de todos los agricultores en el&nbsp;<a href=\"https:\/\/www.nass.usda.gov\/Publications\/AgCensus\/2022\/Full_Report\/Volume_1,_Chapter_1_US\/usv1.pdf\">Censo Agropecuario de 2022<\/a>&nbsp;fue de 58,1 a\u00f1os. Solo el 9 % fueron considerados \u201cagricultores j\u00f3venes\u201d, de 34 a\u00f1os o menos. Estas tendencias tambi\u00e9n se reflejan en el mundo de los productos l\u00e1cteos. Sin embargo, solo el 53 % de todos los productores dijeron que participaban activamente en la planificaci\u00f3n de la herencia o la sucesi\u00f3n, lo que significa que al menos hab\u00edan identificado a un sucesor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo ayudar a que las granjas lecheras familiares prosperen<\/h2>\n\n\n\n<p>En teor\u00eda, comprar m\u00e1s productos l\u00e1cteos elevar\u00eda el valor de mercado de esos productos e influir\u00eda en el precio que los productores reciben por su leche. La sociedad ha hecho eso. El consumo de productos l\u00e1cteos nunca ha sido tan alto, pero la forma en que la gente consume productos l\u00e1cteos ha cambiado.<\/p>\n\n\n\n<p>Los estadounidenses comemos mucho queso, y quiero decir much\u00edsimo. Tambi\u00e9n consumimos una buena cantidad de helado, yogur y mantequilla, pero no tanta leche como antes.<\/p>\n\n\n\n<p>\u00bfSignifica esto que Estados Unidos deber\u00eda cambiar la forma en que se fija el precio de la leche? Tal vez.<\/p>\n\n\n\n<p>Actualmente, la&nbsp;<a href=\"https:\/\/www.ams.usda.gov\/rules-regulations\/moa\/dairy\">FMMO est\u00e1 en proceso de reforma<\/a>&nbsp;, lo que puede ayudar a frenar la oleada de productores lecheros que abandonan la industria. La&nbsp;<a href=\"https:\/\/www.dairyherd.com\/news\/business\/usda-finally-releases-new-federal-milk-marketing-order-recommendations\">reforma se centra en<\/a>&nbsp;reflejar mejor la capacidad de las vacas modernas de producir mayores cantidades de grasa y prote\u00edna; actualizar el apoyo a los costos que reciben los procesadores por el queso, la mantequilla, la leche en polvo descremada y el suero en polvo; y actualizar la forma en que se valora la Clase 1, entre otros cambios. En teor\u00eda, estos cambios pondr\u00edan el precio de la leche en l\u00ednea con el costo de producci\u00f3n en todo el pa\u00eds.<\/p>\n\n\n\n<p>El Departamento de Agricultura de EE. UU. tambi\u00e9n est\u00e1 brindando apoyo a cuatro&nbsp;<a href=\"https:\/\/sdbii.tennessee.edu\/\">Iniciativas <\/a><a href=\"https:\/\/nedairyinnovation.com\/\">de Innovaci\u00f3n <\/a><a href=\"https:\/\/www.dairypcc.net\/\">en Empresas <\/a><a href=\"https:\/\/www.cdr.wisc.edu\/dbia\">L\u00e1cteas<\/a>&nbsp;para ayudar a los productores lecheros a encontrar formas de mantener sus operaciones en funcionamiento para las generaciones futuras a trav\u00e9s de subvenciones, apoyo a la investigaci\u00f3n y asistencia t\u00e9cnica.<a href=\"https:\/\/www.dairypcc.net\/\"><\/a><a href=\"https:\/\/nedairyinnovation.com\/\"><\/a><a href=\"https:\/\/sdbii.tennessee.edu\/\"><\/a><\/p>\n\n\n\n<p>Otra forma de impulsar las lecher\u00edas locales es comprar directamente a un productor. Las operaciones de lecher\u00eda&nbsp;<a href=\"https:\/\/utianews.tennessee.edu\/census-of-agriculture-shows-value-added-agriculture-growth-in-tennessee-to-142-8-million\/\">de valor agregado<\/a>&nbsp;o de granja que producen y venden leche y productos como el queso directamente a los clientes han estado creciendo. Sin embargo, estas operaciones conllevan riesgos financieros para el productor. Ser responsable del orde\u00f1o, el procesamiento y la comercializaci\u00f3n de la leche quita el trabajo ya importante de la producci\u00f3n de leche y agrega dos trabajos m\u00e1s a este. Y los clientes tienen que ser financieramente capaces de pagar un precio m\u00e1s alto por el producto y estar dispuestos a viajar para obtenerlo.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/theconversation.com\/americas-dairy-farms-are-disappearing-down-95-since-the-1970s-milk-price-rules-are-one-reason-why-237439\">https:\/\/theconversation.com\/americas-dairy-farms-are-disappearing-down-95-since-the-1970s-milk-price-rules-are-one-reason-why-237439<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elizabeth Eckelkamp \/ The Conversation Profesor asociado de ciencia animal y especialista en extensi\u00f3n lechera, Universidad de Tennessee Septiembre 16 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[30206,30207,30205,30204],"class_list":["post-85371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-baja-numero-de-granjas-lecheras-en-eu","tag-precio-de-alimentos-eu","tag-precio-de-la-leche-eu","tag-produccion-lechera-eu"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/85371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=85371"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/85371\/revisions"}],"predecessor-version":[{"id":85373,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/85371\/revisions\/85373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/85372"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=85371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=85371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=85371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}