{"id":46465,"date":"2023-02-10T11:37:27","date_gmt":"2023-02-10T17:37:27","guid":{"rendered":"http:\/\/losperiodistas.com.mx\/portal\/?p=46465"},"modified":"2023-02-10T11:37:29","modified_gmt":"2023-02-10T17:37:29","slug":"muere-carlos-saura-la-esencia-del-cine-espanol-el-periodico","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/muere-carlos-saura-la-esencia-del-cine-espanol-el-periodico\/","title":{"rendered":"Muere Carlos Saura, la esencia del cine espa\u00f1ol | El Peri\u00f3dico"},"content":{"rendered":"\n<h2 class=\"has-luminous-vivid-amber-background-color has-background has-medium-font-size wp-block-heading\">El director ha fallecido a los 91 a\u00f1os, un d\u00eda antes de recibir el Goya de Honor<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/b202215b-7d5f-4ed6-9399-9783a1d7ec96_alta-libre-aspect-ratio_default_0-1024x576.jpeg\" alt=\"\" class=\"wp-image-46466\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/b202215b-7d5f-4ed6-9399-9783a1d7ec96_alta-libre-aspect-ratio_default_0-1024x576.jpeg 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/b202215b-7d5f-4ed6-9399-9783a1d7ec96_alta-libre-aspect-ratio_default_0-300x169.jpeg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/b202215b-7d5f-4ed6-9399-9783a1d7ec96_alta-libre-aspect-ratio_default_0-768x432.jpeg 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/b202215b-7d5f-4ed6-9399-9783a1d7ec96_alta-libre-aspect-ratio_default_0.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>LIONEL BONAVENTURE \/ AFP<\/figcaption><\/figure>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-medium-font-size\"><strong>EL PERI\u00d3DICO<\/strong><\/p>\n\n\n\n<p>Se fue Bu\u00f1uel, se fue Berlanga, se fue Bardem. Y nos quedaba<a href=\"https:\/\/www.elperiodico.com\/es\/goya\/20230210\/carlos-saura-cinco-peliculas-clave-82624189\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Carlos Saura,<\/a>\u00a0el m\u00e1s grande de los \u00faltimos cineastas de nuestro tiempo que contribuyeron a forjar la esencia del cine espa\u00f1ol durante la etapa m\u00e1s dif\u00edcil de nuestra historia reciente, durante\u00a0<strong>la dictadura y la transici\u00f3n\u00a0<\/strong>hasta llegar a nuestro presente. Saura nunca dej\u00f3 de filmar y de crear, de ir de un lado a otro con su c\u00e1mara de fotos con la que retrataba el mundo que le rodeaba como si fuera un ap\u00e9ndice de s\u00ed mismo.\u00a0<strong>Carlos Saura, el intr\u00e9pido; Carlos Saura, el mel\u00f3mano; Carlos Saura, el curioso.<\/strong>\u00a0Todo le sorprend\u00eda y a todo sacaba jugo. Carlos Saura, el director de cine, se ha ido a los 91 a\u00f1os,\u00a0<a href=\"https:\/\/www.elperiodico.com\/es\/goya\/20230210\/goya-2023-gala-premios-directo-82733702\" target=\"_blank\" rel=\"noreferrer noopener\">justo un d\u00eda antes de la ceremonia de los Goya en la que deb\u00eda recibir el Premio de Honor.<\/a><\/p>\n\n\n\n<p>M\u00c1S IM\u00c1GENES:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.elperiodico.com\/es\/fotos\/ocio-y-cultura\/muere-carlos-saura-esencia-cine-fotos-82790025\/82792150\">https:\/\/www.elperiodico.com\/es\/fotos\/ocio-y-cultura\/muere-carlos-saura-esencia-cine-fotos-82790025\/82792150<\/a><\/p>\n\n\n\n<p>Naci\u00f3 en Huesca en 1932 y comenz\u00f3 los estudios de ingenier\u00eda industrial, pero los cambi\u00f3 para ingresar en el Instituto de Investigaciones y Experiencias Cinematogr\u00e1ficas de Madrid. En 1952, realiz\u00f3 su primer cortometraje, \u2018La tarde del domingo\u2019, al que le sigui\u00f3 el documental \u2018Cuenca\u2019 y&nbsp;<strong>en 1960 estren\u00f3 &#8216;Los golfos&#8217;<\/strong>, obra fundamental que entroncaba directamente con el neorrealismo italiano trasladado a la realidad espa\u00f1ola. Pero fue<strong>&nbsp;&#8216;La caza&#8217; la pel\u00edcula que lo catapult\u00f3 al \u00e9xito<\/strong>&nbsp;solo cinco a\u00f1os m\u00e1s tarde. \u00bfC\u00f3mo representar mejor la guerra civil espa\u00f1ola sin hablar de ella solo a trav\u00e9s de un punto de vista aleg\u00f3rico?<\/p>\n\n\n\n<figure class=\"wp-block-image is-style-default\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20100401\/carlos-saura-exhibe-deseos-eroticos-264577\"><img decoding=\"async\" src=\"https:\/\/estaticos-cdn.elperiodico.com\/clip\/5464af7c-2864-4b6d-98e5-284c1bbf5fd3_baja-libre-aspect-ratio_default_0.jpg\" alt=\"Uno de los dibujos de Carlos Saura que se exponen en Cuenca.\" title=\"Uno de los dibujos de Carlos Saura que se exponen en Cuenca.\"\/><\/a><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20100401\/carlos-saura-exhibe-deseos-eroticos-264577\">EXPOSICI\u00d3N<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20100401\/carlos-saura-exhibe-deseos-eroticos-264577\">Carlos Saura exhibe sus \u00abdeseos\u00bb er\u00f3ticos<\/a><\/h2>\n\n\n\n<p>A partir de ese momento, esa fue su se\u00f1a de identidad. &#8216;La caza&#8217; sigue constituyendo una de las piedras angulares de la historia de nuestro cine. Pero Carlos Saura\u00a0<strong>no fue autor de una sola obra<\/strong>. Aquello fue solo el principio para desarrollar una trayectoria variada y radical, valiente y repleta de s\u00edmbolos que no hac\u00edan m\u00e1s que interpelar a la realidad del momento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Imprescindible Querejeta<\/h3>\n\n\n\n<p>Su relaci\u00f3n con el productor El\u00edas Querejeta fue fundamental para el desarrollo de su carrera, as\u00ed como para muchos de los autores del momento, como Manuel Guti\u00e9rrez Arag\u00f3n o V\u00edctor Erice. Pero en el caso de Carlos Saura, el t\u00e1ndem era imbatible. \u00bfDe qu\u00e9 otra forma podr\u00eda haberse hecho una pieza tan vanguardista como &#8216;Peppermint Frapp\u00e9&#8217;? \u00bfO &#8216;Stres-es tres-tres&#8217;? Ambos t\u00edtulos configuraron la modernidad del cine espa\u00f1ol y consiguieron sacarlo fuera de nuestras fronteras en un momento especialmente dif\u00edcil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20170924\/personaje-llamado-carlos-saura-6307490\">Un personaje llamado Carlos Saura<\/a><\/h2>\n\n\n\n<p><strong>\u2018La caza\u2019 gan\u00f3 el Oso de Plata en Berl\u00edn&nbsp;<\/strong>y \u2018Peppermint Frapp\u00e9\u2019 consigui\u00f3 el premio al mejor director, que se completar\u00eda con el Oso de Oro en 1981 con \u2018Deprisa, deprisa\u2019, con la que cambi\u00f3 radicalmente de estilo y se acerc\u00f3 al cine quinqui desde una perspectiva tan realista como po\u00e9tica. Pero no solo la Berlinale supo apreciar su val\u00eda. Durante muchos a\u00f1os fue<strong>&nbsp;el \u00fanico director espa\u00f1ol que accedi\u00f3 al Festival de Cannes<\/strong>&nbsp;donde gan\u00f3 el Premio del Jurado por dos de sus dos obras emblem\u00e1ticas, &#8216;La prima Ang\u00e9lica&#8217; y &#8216;Cr\u00eda cuervos&#8217;.<\/p>\n\n\n\n<p>Saura utiliz\u00f3 la met\u00e1fora para hablar&nbsp;<strong>de la represi\u00f3n franquista, de la memoria hist\u00f3rica<\/strong>, del vac\u00edo que sufr\u00eda su generaci\u00f3n, y se encarg\u00f3 de radiografiar todos los males de nuestra sociedad a trav\u00e9s de un estilo simb\u00f3lico, pero al mismo tiempo crudo y revulsivo, combativo. Y lo hizo a trav\u00e9s de pel\u00edculas que contin\u00faan siendo tan enigm\u00e1ticas y fascinantes como &#8216;Ana y los lobos&#8217;, en la que cualquier g\u00e9nero se difumina para dar lugar a un espacio propio donde<strong>&nbsp;se tensa la cuerda entre la raz\u00f3n y la locura, entre la prohibici\u00f3n y la libertad.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Esencia musical<\/h3>\n\n\n\n<p>En 1981 comenzar\u00eda una nueva etapa que le llevar\u00eda a indagar en buena parte de los g\u00e9neros musicales de raigambre latina. Su primera aproximaci\u00f3n fue a trav\u00e9s de la adaptaci\u00f3n de<strong>&nbsp;&#8216;Bodas de sangre&#8217;, de Federico Garc\u00eda Lorca, con Antonio Gades y Cristina Hoyos<\/strong>, a la que dar\u00eda continuidad con &#8216;Carmen&#8217;, en la que seguir\u00eda indagando en torno a las formas y el origen del flamenco. Con \u2018El amor brujo\u2019 culminar\u00eda su trilog\u00eda con Gades, al mismo tiempo que iba intercalando obras de ficci\u00f3n como &#8216;Los zancos&#8217; o la superproducci\u00f3n &#8216;El Dorado&#8217;.<\/p>\n\n\n\n<figure class=\"wp-block-image is-style-default\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20221006\/director-carlos-saura-recibira-goya-76909035\"><img decoding=\"async\" src=\"https:\/\/estaticos-cdn.elperiodico.com\/clip\/2bf7e7d7-5bca-44f1-ad45-11770b7febef_baja-libre-aspect-ratio_default_0.jpg\" alt=\"El director de cine Carlos Saura recibir\u00e1 el Goya de Honor 2023. En la foto, Ena y Antonio\u00a0Saura, hijos de\u00a0Carlos\u00a0Saura, tras el anuncio de que el Goya de Honor 2023 lo recibir\u00e1 \u00e9l por haber dado forma a la historia del cine espa\u00f1ol moderno.\" title=\"El director de cine Carlos Saura recibir\u00e1 el Goya de Honor 2023. En la foto, Ena y Antonio\u00a0Saura, hijos de\u00a0Carlos\u00a0Saura, tras el anuncio de que el Goya de Honor 2023 lo recibir\u00e1 \u00e9l por haber dado forma a la historia del cine espa\u00f1ol moderno.\"\/><\/a><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20221006\/director-carlos-saura-recibira-goya-76909035\">PREMIOS<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20221006\/director-carlos-saura-recibira-goya-76909035\">Y el Goya de Honor es para&#8230; Carlos Saura<\/a><\/h2>\n\n\n\n<p>Regresar\u00eda a la esencia musical, de forma cada vez m\u00e1s conceptual (gracias en parte a la fotograf\u00eda de su aliado Vittorio Storaro), en &#8216;Sevillanas&#8217;, &#8216;Flamenco&#8217;, &#8216;Iberia&#8217;, &#8216;Fados&#8217;, &#8216;Jota de Saura&#8217;, &#8216;Tango&#8217; o &#8216;Flamenco, flamenco&#8217;. Con<strong>&nbsp;&#8216;\u00a1Ay Carmela!&#8217;, protagonizada por Carmen Maura y Andr\u00e9s Pajares,<\/strong>&nbsp;logr\u00f3 el reconocimiento de la Academia del Cine Espa\u00f1ol consiguiendo&nbsp;<strong>13 Goyas.<\/strong>&nbsp;Precisamente este a\u00f1o el director iba a recoger el premio honor\u00edfico por toda su carrera.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De Goya a Bu\u00f1uel<\/h3>\n\n\n\n<p>Tambi\u00e9n abord\u00f3 algunos personajes hist\u00f3ricos relacionados con la pintura, el cine o la creaci\u00f3n art\u00edstica. Le dio a&nbsp;<strong>Francisco Rabal&nbsp;<\/strong>su \u00faltimo gran papel encarnando la figura de Francisco de Goya en &#8216;Goya en Burdeos&#8217; e invent\u00f3 una aventura surrealista entre Luis Bu\u00f1uel, Salvador Dal\u00ed y Federico Garc\u00eda Lorca en&nbsp;<strong>\u2018Bu\u00f1uel y la mesa del rey Salom\u00f3n\u2019.<\/strong><\/p>\n\n\n\n<p>A pesar de su avanzada edad, sigui\u00f3 trabajando y en los \u00faltimos tiempos nos ha regalado piezas como &#8216;Goya 3 de mayo, Rosa Rosae&#8217;, &#8216;La guerra civil&#8217;, &#8216;El Rey de todo el mundo&#8217; y &#8216;Las paredes hablan&#8217;, en la que reflexiona en torno a la creaci\u00f3n a trav\u00e9s de las pinturas rupestres y el arte urbano.<\/p>\n\n\n\n<p><strong>Escribi\u00f3 una novela, \u2018Pajarico solitario\u2019<\/strong>, de corte autobiogr\u00e1fico, que luego llevar\u00eda a la pantalla, realizando la operaci\u00f3n inversa con \u2018Elisa, vida m\u00eda\u2019, que primero fue pel\u00edcula y despu\u00e9s convirti\u00f3 en literatura. Tambi\u00e9n dirigi\u00f3 \u00f3pera, &#8216;Carmen&#8217; y &#8216;Don Giovanni&#8217;, y teatro: &#8216;La fiesta del chivo&#8217;, &#8216;El coronel no tiene quien le escriba&#8217; y &#8216;El gran teatro del mundo&#8217;, de Calder\u00f3n de la Barca.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.elperiodico.com\/es\/goya\/20230210\/muere-carlos-saura-esencia-cine-82506741\">https:\/\/www.elperiodico.com\/es\/goya\/20230210\/muere-carlos-saura-esencia-cine-82506741<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director ha fallecido a los 91 a\u00f1os, un d\u00eda antes de recibir el Goya de Honor EL PERI\u00d3DICO Se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[15096,15097],"class_list":["post-46465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-carlos-saura","tag-cineasta-espanol"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=46465"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46465\/revisions"}],"predecessor-version":[{"id":46467,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46465\/revisions\/46467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/46466"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=46465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=46465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=46465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}