{"id":46442,"date":"2023-02-10T02:43:44","date_gmt":"2023-02-10T08:43:44","guid":{"rendered":"http:\/\/losperiodistas.com.mx\/portal\/?p=46442"},"modified":"2023-02-10T02:43:48","modified_gmt":"2023-02-10T08:43:48","slug":"convocan-alito-y-osorio-chong-a-la-unidad-al-interior-del-pri-la-jornada","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/convocan-alito-y-osorio-chong-a-la-unidad-al-interior-del-pri-la-jornada\/","title":{"rendered":"Convocan &#8216;Alito&#8217; y Osorio Chong a la unidad al interior del PRI\u00a0| La Jornada"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/image_large-1.jpeg\" alt=\"\" class=\"wp-image-46443\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/image_large-1.jpeg 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/image_large-1-300x200.jpeg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2023\/02\/image_large-1-768x512.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>El dirigente nacional del PRI, Alejandro Moreno (c,der) junto con el coordinador de los senadores del tricolor, Miguel \u00c1ngel Osorio Chong (c,der).\u00a0Foto\u00a0<strong>Yazm\u00edn Ortega<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-medium-font-size\"><strong>EMIR OLIVARES ALONSO \/ LA JORNADA<\/strong><\/p>\n\n\n\n<p><em>Ciudad de M\u00e9xico.<\/em>\u00a0El coordinador de los senadores del PRI, Miguel \u00c1ngel Osorio Chong; y el dirigente nacional de ese partido, Alejandro Moreno C\u00e1rdenas, pusieron fin a la controversia que manten\u00edan desde hace varias semanas, y esta noche lanzaron un mensaje de unidad dentro del tricolor.<\/p>\n\n\n\n<p>\u201cVen\u00edamos a restablecer los lazos de trabajo, de coordinaci\u00f3n y de entendimiento del Comit\u00e9 Ejecutivo Nacional (CEN) y con las y los diputados federales, y ese era el objetivo y eso fue lo que se trat\u00f3. Por el bien del partido, por el bien del trabajo legislativo y porque queremos centrar la atenci\u00f3n de las y los pri\u00edstas, junto a los ciudadanos, en ganar la elecci\u00f3n en Coahuila y en el estado de M\u00e9xico\u201d, plante\u00f3 el ex secretario de Gobernaci\u00f3n.<\/p>\n\n\n\n<p>Tras los diferendos entre el coordinador de los senadores del PRI y su dirigente nacional, ambos tuvieron esta tarde una reuni\u00f3n que se realiz\u00f3 en la sede del instituto pol\u00edtico, a la que posteriormente se sumaron las senadoras y senadores del tricolor, as\u00ed como el coordinador del grupo parlamentario en la C\u00e1mara de Diputados, Rub\u00e9n Moreira.<\/p>\n\n\n\n<p>Tras m\u00e1s de tres horas de intercambio y debate, los pri\u00edstas ofrecieron una conferencia de prensa en la que aseguraron que salieron fortalecidos.<\/p>\n\n\n\n<p>\u201cAnte esta controversia que se dio en semanas anteriores, lo que se decidi\u00f3 por parte del grupo parlamentario del PRI (en el Senado), y con una respuesta favorable del presidente del CEN, y con la presencia del coordinador de los diputados, fue el poder tener una reuni\u00f3n, un acercamiento, que nos permitiera trazar camino no de entendimiento solamente,sino de trabajo\u201d, expuso Osorio Chong.<\/p>\n\n\n\n<p>Agreg\u00f3 que durante el encuentro supieron escucharse y ponerse de acuerdo en una ruta hacia el entendimiento, el trabajo y la coordinaci\u00f3n a fin de que con \u201cel mandato del CEN\u201d, logren empatar el trabajo legislativo de la agenda pri\u00edsta tanto en San L\u00e1zaro como en la C\u00e1mara Alta en, dijo, beneficio de la ciudadan\u00eda.PUBLICIDAD<\/p>\n\n\n\n<p>\u201cMientras Morena est\u00e1 s\u00f3lo y \u00fanicamente en campa\u00f1a electoral, que sus funcionarios en lugar de estar en el trabajo que les corresponde, est\u00e1n en campa\u00f1a, el PRI est\u00e1 en su agenda legislativa por el bienestar de la sociedad mexicana en temas como la seguridad; lo econ\u00f3mico, pues es grave lo que est\u00e1 sucediendo en el pa\u00eds; y otros que son fundamentales\u201d.<\/p>\n\n\n\n<p>El coordinador de los senadores del PRI remarc\u00f3 que en el di\u00e1logo con Moreno C\u00e1rdenas \u201cno estuvo en la mesa\u201d la solicitud para su expulsi\u00f3n del partido presentada por algunos sectores de \u00e9ste, y reiter\u00f3 que la enfrentar\u00e1 en los \u00f3rganos internos de la justicia pri\u00edstas.<\/p>\n\n\n\n<p>\u201cEntra en un proceso institucional, legal, que se tiene que enfrentar como cualquier militante. La fortaleza de nuestro instituto pol\u00edtico se da a partir de la pluralidad, esto habla de diferentes voces que pensamos diferente, esto nos hace muy fuertes, as\u00ed naci\u00f3 el PRI, lo enfrentar\u00e9 de manera legal, como se requiere. Pero eso es entretenernos en lo que los corresponde como militantes, lo que nos corresponde como facci\u00f3n, como senadores y como partido es enfocarnos en lo que nos une, que es servir y servir bien y por supuesto para cumplir como partido pol\u00edtico, para ganar las elecciones y vamos a ganar Coahula y vamos a ganar el estado de M\u00e9xico\u201d, enfatiz\u00f3 Osorio Chong.<\/p>\n\n\n\n<p>Por su parte, el l\u00edder nacional tricolor destac\u00f3 que se trat\u00f3 de una reuni\u00f3n donde se antepuso el objetivo del partido: trabajar por su unidad interna y por la de M\u00e9xico, y con ello dar buenos resultados a la ciudadan\u00eda.<\/p>\n\n\n\n<p>\u201cNos hemos reunido para construir una relaci\u00f3n fuerte, s\u00f3lida, muy coordinada con los grupos parlamentarios en el Senado y en la C\u00e1mara de Diputados. Hemos definido los temas estrat\u00e9gicos del pa\u00eds para fortalecer nuestra agenda legislativa y mecanismos de comunicaci\u00f3n, siempre en di\u00e1logo, comunicaci\u00f3n y fortaleza del partido\u201d, expuso Alito.<\/p>\n\n\n\n<p>Remarc\u00f3 que se trat\u00f3 de un encuentro en el que todas las voces fueron escuchadas y donde se acord\u00f3 que el compromiso fundamental es la unidad interna, el respeto basado en el di\u00e1logo y construir un mejor partido, un mejor pa\u00eds y una relaci\u00f3n s\u00f3lida y coordinada entre los pri\u00edstas ante los grandes retos y desaf\u00edos que enfrenta M\u00e9xico.<\/p>\n\n\n\n<p>Celebr\u00f3 la presencia de los coordinadors parlamentarios \u201cen su casa, en la sede del partido\u201d y subray\u00f3 que la fuerza del partido \u201ces la capacidad siempre de sumar, de unir, de pensar en M\u00e9xico, de construir las mejores propuestas y de impulsar en este periodo (en el Congreso) una agenda legislativa robusta, moderna, que resuelva los tema de la sociedad y que nos posicione no s\u00f3lo como una opci\u00f3n pol\u00edtica, sino como la opci\u00f3n pol\u00edtica que tiene experiencia para dar resultados\u201d.<\/p>\n\n\n\n<p>Calcul\u00f3 que la coalici\u00f3n de la que forma parte el PRI triunfar\u00e1 en las pr\u00f3ximas elecciones en Coahuila y estado de M\u00e9xico.<\/p>\n\n\n\n<p>Por su parte, Moreira resalt\u00f3 que en el c\u00f3nclave, que se realiz\u00f3 a puerta cerrada, discutieron las estrategias de ambas bancadas para \u201cenfrentar los retrocesos y hacer propuestas para esta naci\u00f3n. Eso fue lo que platicamos\u201d.<\/p>\n\n\n\n<p>\u201cNos preocupa el incremento de la inflaci\u00f3n, que este mes es alt\u00edsima; el incremento de la pobreza, este pa\u00eds cada vez tiene m\u00e1s pobres; la debilidad de la econom\u00eda sustentada en las remesas de los migrantes; la inseguridad, particularmente del narcotr\u00e1fico que es el peor enemigo de la democracia. Esta fue la reuni\u00f3n, de eso hablamos\u201d, afirm\u00f3 Moreira.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.jornada.com.mx\/notas\/2023\/02\/09\/politica\/convocan-alito-y-osorio-chong-a-la-unidad-al-interior-del-pri\/?from=homeonline&amp;block=politica&amp;opt=articlelink\">https:\/\/www.jornada.com.mx\/notas\/2023\/02\/09\/politica\/convocan-alito-y-osorio-chong-a-la-unidad-al-interior-del-pri\/?from=homeonline&amp;block=politica&amp;opt=articlelink<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EMIR OLIVARES ALONSO \/ LA JORNADA Ciudad de M\u00e9xico.\u00a0El coordinador de los senadores del PRI, Miguel \u00c1ngel Osorio Chong; y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[10782,4573,1978],"class_list":["post-46442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alito-moreno","tag-osorio-chong","tag-pri"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=46442"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46442\/revisions"}],"predecessor-version":[{"id":46444,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46442\/revisions\/46444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/46443"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=46442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=46442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=46442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}