{"id":4184,"date":"2021-02-04T07:12:48","date_gmt":"2021-02-04T13:12:48","guid":{"rendered":"http:\/\/losperiodistas.com.mx\/portal\/?p=4184"},"modified":"2021-02-04T07:12:48","modified_gmt":"2021-02-04T13:12:48","slug":"dia-mundial-contra-el-cancer-puede-una-vacuna-erradicar-la-otra-pandemia-del-siglo-xxi-en","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/dia-mundial-contra-el-cancer-puede-una-vacuna-erradicar-la-otra-pandemia-del-siglo-xxi-en\/","title":{"rendered":"D\u00eda Mundial contra el C\u00e1ncer: \u00bfPuede una vacuna erradicar la otra pandemia del siglo XXI? | EN"},"content":{"rendered":"\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size\">MARTA RODR\u00cdGUEZ MART\u00cdNEZ \/ EURONEWS<\/p>\n\n\n\n<p>No solo se muri\u00f3 de COVID-19 en 2020. En el mismo a\u00f1o,&nbsp;<strong>unas 10 millones de personas<\/strong>&nbsp;fallecieron por c\u00e1ncer, m\u00e1s de cinco veces m\u00e1s que por el nuevo coronavirus, seg\u00fan datos publicados por la Organizaci\u00f3n Mundial de la Salud (OMS) con motivo del&nbsp;<strong>D\u00eda Mundial contra el C\u00e1ncer<\/strong>.<\/p>\n\n\n\n<p>A estas muertes, se sumaron las\u00a0<strong>v\u00edctimas colaterales<\/strong>\u00a0de la situaci\u00f3n de emergencia que vieron c\u00f3mo recib\u00edan un diagn\u00f3stico tard\u00edo o sufr\u00edan retrasos en el inicio de sus tratamientos por la saturaci\u00f3n de los sistemas sanitarios de sus pa\u00edses.<\/p>\n\n\n\n<p>Entre marzo y junio de 2020, a consecuencia del confinamiento, se detectaron en Espa\u00f1a&nbsp;<strong>un 21% menos de nuevos casos<\/strong>, seg\u00fan datos de la Asociaci\u00f3n Espa\u00f1ola de Comunicaci\u00f3n Cient\u00edfica (AECC).<\/p>\n\n\n\n<p>Sin embargo, el c\u00e1ncer no dio tregua, con 19,3 millones diagn\u00f3sticos en el \u00faltimo a\u00f1o, en todo el mundo. Actualmente&nbsp;<strong>una de cada cinco personas padecer\u00e1 c\u00e1ncer a lo largo de su vida<\/strong>. La OMS advierte que para 2040 el n\u00famero aumentar\u00e1n hasta en un 50%.<\/p>\n\n\n\n<p><strong>Con las vacunas m\u00e1s que nunca de plena actualidad, \u00bfpodr\u00edan poner fin no solo a la pandemia del coronavirus?<\/strong><\/p>\n\n\n\n<p>Las vacunas se administran para conseguir una inmunidad duradera al inocular partes atenuadas o inactivadas de una enfermedad para ense\u00f1ar al sistema inmunitario a defenderse.<\/p>\n\n\n\n<p>La \u00fanica enfermedad que ha sido&nbsp;<strong>completamente erradicada gracias a la vacunaci\u00f3n ha sido la viruela<\/strong>, un virus con altas tasas de mortalidad &#8211; el 30% de los infectados fallec\u00eda &#8211; y que se caracterizaba por la aparici\u00f3n de p\u00fastulas pudiendo desencadenar en una fatal respuesta inflamatoria.<\/p>\n\n\n\n<p>La \u00faltima persona diagnosticada con esta enfermedad&nbsp;<strong>data de 1977<\/strong>, tres a\u00f1os m\u00e1s tarde la OMS certific\u00f3 su erradicaci\u00f3n.<\/p>\n\n\n\n<p>El final lo escribi\u00f3 una vacuna que consist\u00eda en inyectar el virus&nbsp;<em>vaccinia<\/em>, aislado por primera vez en caballos y similar al de la viruela, en personas sanas para producir una enfermedad leve y educar al sistema inmunol\u00f3gico antes de que se contagiara del letal virus.<\/p>\n\n\n\n<p>Aunque este ha sido el caso m\u00e1s exitoso, la lista de enfermedades que la vacunaci\u00f3n ha conseguido reducir a su m\u00ednima expresi\u00f3n es extensa: difteria, poliomielitis, sarampi\u00f3n, t\u00e9tanos&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las vacunas que ya existen contra el c\u00e1ncer<\/h2>\n\n\n\n<p>En la actualidad ya existen vacunas que pueden prevenir algunos tipos de c\u00e1ncer, pero el reto es que la mayor\u00eda de los casos&nbsp;<strong>no tienen su origen en un agente infeccioso<\/strong>&nbsp;como un virus o una bacteria, explica a Euronews el investigador Rub\u00e9n P\u00edo, director del Programa de Tumores S\u00f3lidos de la Universidad de Navarra.<\/p>\n\n\n\n<p><strong>\u00abHay que distinguir entre vacunas preventivas y terap\u00e9uticas\u00bb<\/strong>, se\u00f1ala P\u00edo, \u00abla vacuna de la COVID, por ejemplo, es preventiva porque la recibes cuando est\u00e1s sano para activar los mecanismos de defensa contra el agente infeccioso\u00bb.<\/p>\n\n\n\n<p>As\u00ed tambi\u00e9n se puede entrenar al sistema inmunitario a defenderse de los virus que pueden provocar c\u00e1ncer, pero&nbsp;<strong>solo un 25% de los casos son causados por una infecci\u00f3n<\/strong>, seg\u00fan datos de la OMS.<\/p>\n\n\n\n<p>Por tanto, el campo de las vacunaci\u00f3n preventiva contra el c\u00e1ncer no es muy extenso, pero existen ejemplos.<\/p>\n\n\n\n<p>La m\u00e1s extendida es&nbsp;<strong>la vacuna contra el virus del papiloma humano (VPH)<\/strong>, indica P\u00edo, que es una infecci\u00f3n que puede causar c\u00e1nceres de cuello de \u00fatero o de garganta, entre otros. Otra vacuna que puede prevenir algunos casos de c\u00e1ncer, en concreto el de h\u00edgado, es la de la&nbsp;<strong>hepatitis B<\/strong>.<\/p>\n\n\n\n<p>Pero las posibilidades de la vacunaci\u00f3n contra el c\u00e1ncer no solo se limitan a la prevenci\u00f3n. \u00abTambien puedes utilizar vacunas terap\u00e9uticas, que ense\u00f1an a tu sistema inmune a reconocer el tumor cuando ya est\u00e1 presente\u00bb, explica el investigador.<\/p>\n\n\n\n<p>P\u00edo cita por ejemplo la vacuna Heberprovac para tratar el&nbsp;<strong>c\u00e1ncer de pr\u00f3stata avanzado<\/strong>&nbsp;desarrollada por cient\u00edficos cubanos y que ampli\u00f3 su ensayo cl\u00ednico en 2019.<\/p>\n\n\n\n<p>Otro ejemplo, se\u00f1ala el investigador, es&nbsp;<strong>la terapia del bacilo de Calmette-Gu\u00e9rin (BCG)<\/strong>&nbsp;que se utiliza para tratar el c\u00e1ncer de vejiga \u00abinyectando un virus atenuado parecido al de la tuberculosis para generar una respuesta inmune que ataca al tumor\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una enfermedad distinta en cada persona<\/h2>\n\n\n\n<p>Otro gran obst\u00e1culo de la vacunaci\u00f3n contra el c\u00e1ncer es que la enfermedad es distinta en el genoma de cada persona, a diferencia de lo que puede ocurrir con un virus como el del coronavirus que es universal.<\/p>\n\n\n\n<p>Con el c\u00e1ncer, P\u00edo explica que los da\u00f1os en el ADN de cada persona cambian y se necesita algo especifico de ese tumor para hacer una vacuna, por ejemplo,&nbsp;<strong>no hay un ant\u00edgeno universal para todos los c\u00e1nceres de pulm\u00f3n.<\/strong><\/p>\n\n\n\n<p>\u00abNo solo no hay dos c\u00e1nceres iguales, sino que en la misma persona va evolucionando\u00bb, se\u00f1ala el investigador, por eso hay tratamientos que dejan de funcionar despu\u00e9s de un tiempo en algunos pacientes. \u00abNunca se puede decir nunca en ciencia pero parece dificil que se puedan secuenciar las alteraciones de un tumor en concreto para dise\u00f1ar una vacuna universal\u00bb.<\/p>\n\n\n\n<p>La investigaci\u00f3n est\u00e1 avanzando hacia la medicina oncol\u00f3gica pesonalizada, gracias al desarrollo del conocimiento sobre el genoma humano y de tecnolog\u00edas que&nbsp;<strong>permiten secuenciar las alteraciones espec\u00edficas de cada paciente<\/strong>, explica P\u00edo.<\/p>\n\n\n\n<p>La clave de todos estos avances &#8211; que se engloban en&nbsp;<strong>el campo de la inmunoterapia<\/strong>&nbsp;&#8211; es comprender c\u00f3mo responden las defensas del cuerpo al ataque de las c\u00e9lulas tumorales. Las vacunas son solo una de sus estrategias, se\u00f1ala P\u00edo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La esperanza en el sistema inmune<\/h2>\n\n\n\n<p>El c\u00e1ncer ha sido&nbsp;<strong>la primera causa de muerte durante el \u00faltimo medio siglo<\/strong>, comenzaba su discurso de aceptaci\u00f3n del Premio Nobel de Medicina el inmun\u00f3logo japon\u00e9s Tasuku Honjo, y la tendencia se agrava a\u00fan m\u00e1s a medida que aumenta la esperanza media de vida.<\/p>\n\n\n\n<p>Reside en&nbsp;<strong>descifrar los secretos de nuestros sofisticados sistemas inmunitarios<\/strong>&nbsp;que este pron\u00f3stico no sea l\u00fagubre.<\/p>\n\n\n\n<p>As\u00ed lo explicaba Hojo al recibir el mayor galard\u00f3n en el campo de la Medicina en 2018 por sus avances en el tratamiento del c\u00e1ncer a trav\u00e9s de la inmunoterapia:<\/p>\n\n\n\n<p>\u00ab<strong>\u00bfC\u00f3mo pudimos desarrollar un sistema de reconocimiento inmunol\u00f3gico tan sofisticado que emplea el reordenamiento gen\u00e9tico?<\/strong>&nbsp;El mecanismo de reordenamiento gen\u00e9tico debe haberse desarrollado accidentalmente, probablemente hace unos quinientos millones de a\u00f1os, cuando los vertebrados evolucionaron. A partir de entonces, debi\u00f3 de persistir a trav\u00e9s de la selecci\u00f3n natural debido a la ventaja de sobrevivir a las enfermedades infecciosas\u00bb.<\/p>\n\n\n\n<p>Y concluye: \u00abTeniendo en cuenta que la probabilidad de tal mutaci\u00f3n y selecci\u00f3n debe ser incre\u00edblemente baja,&nbsp;<strong>los seres humanos somos muy afortunados<\/strong>\u00ab.<\/p>\n\n\n\n<p>Los avances en Medicina se centran en que nuestra suerte como especie un d\u00eda nos pueda llegar a inmunizar contra todo tipo de c\u00e1ncer.<\/p>\n\n\n\n<p>Fuente: https:\/\/es.euronews.com\/2021\/02\/04\/dia-mundial-contra-el-cancer-puede-una-vacuna-erradicar-la-otra-pandemia-del-siglo-xxi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARTA RODR\u00cdGUEZ MART\u00cdNEZ \/ EURONEWS No solo se muri\u00f3 de COVID-19 en 2020. En el mismo a\u00f1o,&nbsp;unas 10 millones de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=4184"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4184\/revisions"}],"predecessor-version":[{"id":4186,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4184\/revisions\/4186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/4185"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=4184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=4184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=4184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}