{"id":27260,"date":"2022-05-08T19:38:46","date_gmt":"2022-05-09T00:38:46","guid":{"rendered":"http:\/\/losperiodistas.com.mx\/portal\/?p=27260"},"modified":"2022-05-08T19:38:47","modified_gmt":"2022-05-09T00:38:47","slug":"lopez-obrador-condena-en-la-habana-el-embargo-de-eeuu-y-pide-a-cuba-que-la-revolucion-sea-capaz-de-renovarse-el-pais","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/lopez-obrador-condena-en-la-habana-el-embargo-de-eeuu-y-pide-a-cuba-que-la-revolucion-sea-capaz-de-renovarse-el-pais\/","title":{"rendered":"L\u00f3pez Obrador condena en La Habana el embargo de EEUU y pide a Cuba que \u201cla revoluci\u00f3n sea capaz de renovarse\u201d | El Pa\u00eds"},"content":{"rendered":"\n<p><em>El presidente mexicano recibe en Cuba la Orden Jos\u00e9 Mart\u00ed durante una visita de alto simbolismo pol\u00edtico<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"734\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/GUP5QITY5EUW4WEBUUVBJWV4TY-1024x734.jpeg\" alt=\"\" class=\"wp-image-27261\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/GUP5QITY5EUW4WEBUUVBJWV4TY-1024x734.jpeg 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/GUP5QITY5EUW4WEBUUVBJWV4TY-300x215.jpeg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/GUP5QITY5EUW4WEBUUVBJWV4TY-768x551.jpeg 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/GUP5QITY5EUW4WEBUUVBJWV4TY-1536x1101.jpeg 1536w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/GUP5QITY5EUW4WEBUUVBJWV4TY.jpeg 1960w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>El presidente cubano Miguel D\u00edaz-Canel saluda a Andr\u00e9s Manuel L\u00f3pez Obrador, en La Habana. YAMIL LAGE (AFP)<\/figcaption><\/figure>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size\">MAURICIO VICENTE \/ La Habana \/ EL PA\u00cdS<\/p>\n\n\n\n<p>Hasta qu\u00e9 punto el viaje a La Habana del presidente mexicano,&nbsp;<a href=\"https:\/\/elpais.com\/noticias\/andres-manuel-lopez-obrador\/\" target=\"_blank\" rel=\"noreferrer noopener\">Andr\u00e9s Manuel L\u00f3pez Obrador<\/a>, se traducir\u00e1 en hechos concretos que hagan avanzar las relaciones bilaterales, la historia dir\u00e1. De momento, este domingo&nbsp;<a href=\"https:\/\/elpais.com\/internacional\/2022-05-08\/lopez-obrador-recibe-en-cuba-la-orden-jose-marti-durante-una-visita-de-alto-simbolismo-politico.html\" target=\"_blank\" rel=\"noreferrer noopener\">el mexicano fue condecorado en Cuba con la Orden Jos\u00e9 Mart\u00ed,<\/a>&nbsp;la m\u00e1s alta distinci\u00f3n que conceden las autoridades de la isla a una personalidad extranjera, y con eso queda dicho casi todo. M\u00e1s all\u00e1 de los acuerdos que suscribieron ambos pa\u00edses, que fueron sobre todo declaraciones de buenas intenciones, para el Gobierno de Miguel D\u00edaz-Canel la visita fue importante por el apoyo pol\u00edtico que represent\u00f3, pues en tierras cubanas L\u00f3pez Obrador volvi\u00f3 a denunciar con toda contundencia el embargo norteamericano contra la isla, que dura ya seis d\u00e9cadas y La Habana considera la principal causa de sus males econ\u00f3micos.<\/p>\n\n\n\n<p>El presidente mexicano critic\u00f3 a EEUU por su pol\u00edtica de asfixia contra la isla para tratar de forzar un empeoramiento de la situaci\u00f3n econ\u00f3mica que lleve a la poblaci\u00f3n a levantarse contra el Gobierno, \u201calgo que no parece probable\u201d, se\u00f1al\u00f3, aunque advirti\u00f3 que si ello ocurriese ser\u00eda \u201cun triunfo vil y canalla\u201d de Washington. Se ofreci\u00f3 a usar sus buenos oficios con el presidente estadounidense, Joe Biden, para que entienda que \u201ces tiempo de di\u00e1logo\u201d con Cuba y no de confrontaci\u00f3n, y que deben restablecerse relaciones normales entre ambos pa\u00edses. \u201cEs el momento de una nueva convivencia\u201d, asegur\u00f3, en un largo discurso en el que repas\u00f3 los v\u00ednculos bilaterales y mencion\u00f3 a los grandes pr\u00f3ceres de la independencia de Cuba y el apoyo que recibieron de M\u00e9xico para lograrla.<\/p>\n\n\n\n<p>\u201cNunca he apostado ni apostare al fracaso de la Revoluci\u00f3n cubana, a su legado de justicia y a sus lecciones de independencia y dignidad\u201d, afirm\u00f3, pero al mismo tiempo lanz\u00f3 un mensaje a La Habana de que era necesario hacer cambios: \u201cprefiero seguir manteniendo la esperanza de que la Revoluci\u00f3n renazca en la Revoluci\u00f3n, de que la Revoluci\u00f3n sea capaz de renovarse para seguir el ejemplo de los m\u00e1rtires que lucharon por la libertad\u201d. Dijo que cre\u00eda que \u201cse est\u00e1n haciendo las cosas con ese prop\u00f3sito\u201d, y que eso ser\u00eda \u201cla segunda gran lecci\u00f3n de Cuba para el mundo\u201d.<\/p>\n\n\n\n<p>L\u00f3pez Obrador tambi\u00e9n rechaz\u00f3 la exclusi\u00f3n de Cuba (y de Nicaragua y Venezuela) de la pr\u00f3xima Cumbre de Las Am\u00e9ricas, convocada por Joe Biden el pr\u00f3ximo mes de junio en la ciudad de Los \u00c1ngeles, y se comprometi\u00f3 a insistir con el presidente norteamericano para que no haya pa\u00edses vetados. En estos momentos este tema pesa mucho en La Habana, m\u00e1s despu\u00e9s de los pronunciamientos de varios pa\u00edses de la Comunidad del Caribe (Caricom), que se han plantado y advertido a Washington que si persiste en las exclusiones ellos no acudir\u00e1n. Son 14 pa\u00edses, y que L\u00f3pez Obrador est\u00e9 firmemente al lado de la isla en este asunto es relevante, ya que M\u00e9xico no es un pa\u00eds latinoamericano cualquiera.<\/p>\n\n\n\n<p>Tras las palabras del mexicano, el presidente cubano, Miguel D\u00edaz-Canel, le agradeci\u00f3 sus \u201cfirmes y reiteradas declaraciones a favor del cese del bloqueo genocida\u201d. En v\u00edsperas de la visita, ya hab\u00eda saludado al presidente mexicano por su persistente defensa de la revoluci\u00f3n y su elogios a la \u201cdignidad y esp\u00edritu de resistencia\u201d del pueblo cubano. \u201cEsos son los pilares m\u00e1s s\u00f3lidos en los que se asientan nuestras relaciones\u201d, dijo entonces D\u00edaz-Canel.<\/p>\n\n\n\n<p>El viaje no solo fue importante para Cuba, sino tambi\u00e9n para L\u00f3pez Obrador, que ha hecho una bandera de su pol\u00edtica de respaldo activo a La Habana frente a EEUU. A diferencia de otros presidentes mexicanos \u2013todos han visitado Cuba desde 1959, pero la mayor\u00eda lo han hecho al terminar su mandato, de un modo protocolar-, L\u00f3pez Obrador lleg\u00f3 a mitad de legislatura y despu\u00e9s de haber visitado tres veces Estados Unidos, escenificando que quiere dar el m\u00e1ximo nivel a las relaciones entre los dos pa\u00edses en consonancia con la tradici\u00f3n que el Partido Revolucionario Institucional (PRI)&nbsp;<a href=\"https:\/\/elpais.com\/mexico\/2021-09-16\/lopez-obrador-hace-del-dia-de-la-independencia-un-alegato-en-defensa-de-cuba.html\" target=\"_blank\" rel=\"noreferrer noopener\">mantuvo durante d\u00e9cadas, siguiendo la filosof\u00eda de que<\/a>&nbsp;\u201cal defender a Cuba se defiende tambi\u00e9n a M\u00e9xico y sus principios\u201d.<\/p>\n\n\n\n<p>En qu\u00e9 medida los resultados del viaje superan su simbolismo, que es mucho, se ver\u00e1. Durante su estancia -de 24 horas- en La Habana, L\u00f3pez Obrador sostuvo conversaciones oficiales con Miguel D\u00edaz-Canel y asisti\u00f3 junto a \u00e9l a la firma de dos documentos bilaterales: uno en el sector de la salud, en el que ambos pa\u00edses expresaron su voluntad de fortalecer la cooperaci\u00f3n para \u201cpromover la capacitaci\u00f3n de sus recursos humanos y de estimular la investigaci\u00f3n y la asistencia en diferentes \u00e1reas de la salud\u201d, pero sin mencionar la posible adquisici\u00f3n por M\u00e9xico de medicinas y vacunas contra la covid-19 desarrolladas por los laboratorios cubanos, que se est\u00e1 valorando; y otra declaraci\u00f3n, de car\u00e1cter pol\u00edtico, rubricada por los propios D\u00edaz-Canel y L\u00f3pez Obrador, en la que escuetamente expresaron su inter\u00e9s por \u201ccontinuar fortaleciendo los hist\u00f3ricos v\u00ednculos de hermandad y fraternidad entre ambos pa\u00edses\u201d y \u201cconsolidar una nueva etapa en la relaci\u00f3n bilateral\u201d.<\/p>\n\n\n\n<p>Nada se dijo p\u00fablicamente de la posibilidad de que instituciones financieras mexicanas puedan asistir a sus inversores y fortalecer el comercio bilateral \u2013en estos momentos los intercambios rondan los 400 millones de d\u00f3lares anuales, cifra que sit\u00faa a M\u00e9xico entre los 10 primeros socios de La Habana-, y tampoco de ampliar las capacidades del Consulado en La Habana, en momentos de gran presi\u00f3n migratoria. En los \u00faltimos dos meses, 67.000 emigrantes ilegales cubanos han entrado a EEUU por la frontera mexicana, un r\u00e9cord absoluto. A M\u00e9xico le interesa promover una emigraci\u00f3n legal y segura, no que estos emigrantes vayan cruzando fronteras y caigan en manos de mafias, pero para ello es indispensable que el consulado pueda recuperar el ritmo anterior a la pandemia \u2013en 2018 se concedieron 24.000 visados a ciudadanos cubanos, este a\u00f1o cuando m\u00e1s se llegar\u00e1 a 18.000-. Aunque el tema migratorio fue el eje de la gira centroamericana de L\u00f3pez Obrador, en La Habana el tono fue otro y ni sali\u00f3 en las declaraciones oficiales.<\/p>\n\n\n\n<p>Algunos analistas destacaron que no era casualidad el hecho de que L\u00f3pez Obrador viajara a La Habana con una peque\u00f1a comitiva que incluy\u00f3 al canciller, Marcelo Ebrard, y a los secretarios de Defensa, Luis Crescencio Sandoval, y de Marina, Jos\u00e9 Rafael Ojeda. Seg\u00fan declar\u00f3 a la revista&nbsp;<em>Proceso<\/em>&nbsp;Arturo L\u00f3pez-Levy, profesor de relaciones internacionales de la Universidad Holy Names, de California, \u201cL\u00f3pez Obrador quiere que sus militares intercambien ideas y conceptos doctrinales con militares de izquierda y que vean c\u00f3mo los militares cubanos se han insertado en l\u00f3gicas de seguridad nacional que van m\u00e1s all\u00e1 de la defensa e incluyen temas como la lucha contra la pobreza, el manejo de empresas estrat\u00e9gicas y el desarrollo econ\u00f3mico\u201d. Sea esta apreciaci\u00f3n acertada o no, s\u00ed qued\u00f3 clara la gran carga simb\u00f3lica y pol\u00edtica de la visita para ambos pa\u00edses. Antes de regresar a M\u00e9xico en la noche del domingo, el presidente mexicano ten\u00eda previsto encontrarse con intelectuales y artistas cubanos con los que guarda una relaci\u00f3n de amistad desde hace tiempo, como los cantantes Silvio Rodr\u00edguez y Amaury P\u00e9rez Vidal. Otro gui\u00f1o m\u00e1s al imaginario com\u00fan.<\/p>\n\n\n\n<p><a href=\"https:\/\/plus.elpais.com\/newsletters\/lnp\/1\/348\"><strong>Suscr\u00edbase aqu\u00ed<\/strong><\/a>a la\u00a0<em>newsletter<\/em>\u00a0de EL PA\u00cdS M\u00e9xico y reciba todas las claves informativas de la actualidad de este pa\u00eds<\/p>\n\n\n\n<p>Fuente: https:\/\/elpais.com\/mexico\/2022-05-08\/lopez-obrador-condena-en-la-habana-el-embargo-de-eeuu-y-pide-a-cuba-que-la-revolucion-sea-capaz-de-renovarse.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente mexicano recibe en Cuba la Orden Jos\u00e9 Mart\u00ed durante una visita de alto simbolismo pol\u00edtico MAURICIO VICENTE \/ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[9963,9980,2997,9981,9979],"class_list":["post-27260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-amlo-cuba","tag-bloque-a-cuba","tag-eeuu","tag-embargo-economico-cuba","tag-revolucion-cubana"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=27260"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27260\/revisions"}],"predecessor-version":[{"id":27262,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27260\/revisions\/27262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/27261"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=27260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=27260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=27260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}