{"id":27257,"date":"2022-05-08T19:17:28","date_gmt":"2022-05-09T00:17:28","guid":{"rendered":"http:\/\/losperiodistas.com.mx\/portal\/?p=27257"},"modified":"2022-05-08T19:17:30","modified_gmt":"2022-05-09T00:17:30","slug":"renuncia-victor-hernandez-a-la-direccion-del-seneam-en-medio-de-incidentes-aereos-el-financiero","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/renuncia-victor-hernandez-a-la-direccion-del-seneam-en-medio-de-incidentes-aereos-el-financiero\/","title":{"rendered":"Renuncia V\u00edctor Hern\u00e1ndez a la direcci\u00f3n del SENEAM, en medio de incidentes a\u00e9reos | El Financiero"},"content":{"rendered":"\n<p>V\u00edctor Her<em>n\u00e1ndez, titular de Servicios a la Navegaci\u00f3n en el Espacio A\u00e9reo Mexicano, anunci\u00f3 que dejar\u00e1 su puesto a partir de este lunes 9 de mayo.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/7UCOZJIXFFHCDNKB6XEKJQDYRU.jpeg\" alt=\"\" class=\"wp-image-27258\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/7UCOZJIXFFHCDNKB6XEKJQDYRU.jpeg 800w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/7UCOZJIXFFHCDNKB6XEKJQDYRU-300x199.jpeg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2022\/05\/7UCOZJIXFFHCDNKB6XEKJQDYRU-768x510.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>V\u00edctor Hern\u00e1ndez Sandoval dejar\u00e1 su cargo en el SENEAM a partir de este lunes 9 de mayo.\u00a0(Daniel Augusto\/Daniel Augusto)<\/figcaption><\/figure>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size\">ALDO MUNGU\u00cdA \/ EL FINANCIERO<\/p>\n\n\n\n<p>V\u00edctor Hern\u00e1ndez, titular de<strong>&nbsp;Servicios a la Navegaci\u00f3n en el Espacio A\u00e9reo Mexicano (SENEAM)<\/strong>, present\u00f3 una renuncia de forma irrevocable a su puesto, esto en medio de&nbsp;<strong>reportes de incidentes a\u00e9reos graves<\/strong>&nbsp;en el Valle de M\u00e9xico.<\/p>\n\n\n\n<p>En una carta enviada al secretario de Infraestructura, Comunicaciones y Transportes, el controlador de tr\u00e1nsito a\u00e9reo detall\u00f3 que\u00a0<strong>dejar\u00e1 el puesto a partir de este lunes 9 de mayo<\/strong>, despu\u00e9s de haber desempe\u00f1ado el papel de director desde diciembre de 2018.<\/p>\n\n\n\n<p>El SENEAM fue la dependencia encargada del redise\u00f1o del espacio a\u00e9reo y la que asegur\u00f3 que la&nbsp;<a href=\"https:\/\/www.elfinanciero.com.mx\/nacional\/2022\/05\/05\/vuela-vuela-asi-luce-el-espacio-aereo-en-el-aifa-y-el-aicm\/\" target=\"_blank\" rel=\"noreferrer noopener\">confluencia de los aeropuertos de Santa Luc\u00eda y el de la Ciudad de M\u00e9xico&nbsp;<\/a>era posible.<\/p>\n\n\n\n<p>No obstante, desde la implementaci\u00f3n del redise\u00f1o del espacio a\u00e9reo en marzo del 2021,\u00a0<strong>tripulaciones y controladores a\u00e9reos han registrado incidentes graves<\/strong>, como la activaci\u00f3n de alarmas contra colisi\u00f3n, eventos de idas al aire cada vez m\u00e1s frecuentes, entre otros, que no han sido atendidos por las autoridades.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.elfinanciero.com.mx\/resizer\/PvhFZ2mW0RvoIZpxwkI3Ee3FTOo=\/1440x0\/filters:format(jpg):quality(70)\/cloudfront-us-east-1.images.arcpublishing.com\/elfinanciero\/DWZUFEKMU5EBNCSHNC2CXZ442A.jpeg\" alt=\"\"\/><figcaption><strong>Carta de renuncia.&nbsp;<\/strong>(Especial)<\/figcaption><\/figure>\n\n\n\n<p>Y es que, el pasado jueves 5 de mayo, la&nbsp;<strong>Asociaci\u00f3n Sindical de Pilotos Aviadores de M\u00e9xico (ASPA)&nbsp;<\/strong>solicit\u00f3 una reuni\u00f3n con las autoridades aeron\u00e1uticas mexicanas con el objetivo de abordar la problem\u00e1tica de navegaci\u00f3n que existe en el<a href=\"https:\/\/www.elfinanciero.com.mx\/cdmx\/2022\/05\/05\/pilotos-piden-reunion-con-autoridades-para-abordar-problema-de-navegacion-en-aicm-y-aifa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><u><strong>Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) y en el nuevo Aeropuerto Internacional Felipe \u00c1ngeles (AIFA)<\/strong><\/u><\/a>.<\/p>\n\n\n\n<p>Ello, despu\u00e9s de que durante el \u00faltimo mes se registraran incidentes de aeronaves que llegan al AICM, como&nbsp;<strong>bajos niveles de combustible y desv\u00edos por la saturaci\u00f3n&nbsp;<\/strong>en dicho puerto a\u00e9reo.<\/p>\n\n\n\n<p>Por otra parte, la\u00a0<strong>IFALPA\u00a0<\/strong>remarc\u00f3 que<strong>\u00a0la apertura del AIFA ha tra\u00eddo nuevas complicaciones para los controladores a\u00e9reos<\/strong>, que al parecer no recibieron la capacitaci\u00f3n necesaria para operar el redise\u00f1o del espacio a\u00e9reo en el Valle de M\u00e9xico.<\/p>\n\n\n\n<p>\u201cParecer\u00eda que, con la apertura de este aeropuerto recientemente convertido, los controladores de tr\u00e1nsito a\u00e9reo, aparentemente recibieron poca capacitaci\u00f3n y apoyo sobre c\u00f3mo operar esta nueva configuraci\u00f3n en el espacio a\u00e9reo\u201d, remarc\u00f3 en un aviso la Federaci\u00f3n.<\/p>\n\n\n\n<p>Fuente: https:\/\/www.elfinanciero.com.mx\/nacional\/2022\/05\/08\/renuncia-victor-hernandez-a-la-direccion-del-seneam-en-medio-de-incidentes-aereos\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edctor Hern\u00e1ndez, titular de Servicios a la Navegaci\u00f3n en el Espacio A\u00e9reo Mexicano, anunci\u00f3 que dejar\u00e1 su puesto a partir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[5803,7997,9978,9977],"class_list":["post-27257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-controladores-aereos","tag-seneam","tag-trafico-aereo-cdmx","tag-victor-hernandez-sandoval"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=27257"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27257\/revisions"}],"predecessor-version":[{"id":27259,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27257\/revisions\/27259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/27258"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=27257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=27257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=27257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}