{"id":126427,"date":"2026-07-13T10:21:23","date_gmt":"2026-07-13T16:21:23","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=126427"},"modified":"2026-07-13T10:21:25","modified_gmt":"2026-07-13T16:21:25","slug":"ariadna-vilalta-la-ciberpsicologa-que-advierte-del-impacto-de-la-tecnologia-en-nuestra-conducta-estamos-participando-en-el-mayor-experimento-psicologico-de-la-historia-sin-haber-leido-las-instrucc","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/ariadna-vilalta-la-ciberpsicologa-que-advierte-del-impacto-de-la-tecnologia-en-nuestra-conducta-estamos-participando-en-el-mayor-experimento-psicologico-de-la-historia-sin-haber-leido-las-instrucc\/","title":{"rendered":"Ariadna Vilalta, la ciberpsic\u00f3loga que advierte del impacto de la tecnolog\u00eda en nuestra conducta: \u00abEstamos participando en el mayor experimento psicol\u00f3gico de la historia sin haber le\u00eddo las instrucciones\u00bb | PAPEL"},"content":{"rendered":"\n<p class=\"has-pale-cyan-blue-background-color has-background has-medium-font-size\">Por su libro &#8216;Una vida siempre en l\u00ednea&#8217; desfilan expertos y casos cl\u00ednicos con los que ofrece recursos para combatir las consecuencias de la adicci\u00f3n digital<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"852\" height=\"1024\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/17838669093665-852x1024.jpeg\" alt=\"\" class=\"wp-image-126428\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/17838669093665-852x1024.jpeg 852w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/17838669093665-249x300.jpeg 249w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/17838669093665-768x923.jpeg 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/17838669093665.jpeg 1220w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-e3c5a5779b9e42ab53514152c96df566\"><strong>Ismael Marinero \/ PAPEL<\/strong><\/p>\n\n\n\n<p>Madrid<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Downton Abbey<\/em>, la exitosa serie de \u00e9poca de Netflix, empieza con un telegrama. La c\u00e1mara sigue las l\u00edneas del tel\u00e9grafo y toda la trama se despliega gracias a la intervenci\u00f3n de una tecnolog\u00eda que supuso el primer paso hacia la&nbsp;<strong>hiperconexi\u00f3n digital&nbsp;<\/strong>que nos ahoga hoy en d\u00eda bajo una lluvia constante de notificaciones.<\/p>\n\n\n\n<p>Si el tel\u00e9grafo y la electricidad transformaron profundamente la sociedad a mediados del siglo XIX, la llegada de internet, las redes sociales y la inteligencia artificial (IA) la est\u00e1 poniendo patas arriba a una velocidad tan vertiginosa que es imposible seguir el ritmo. Y eso se est\u00e1 notando, y mucho, en nuestro maleable, complejo y fr\u00e1gil cerebro de&nbsp;<em>Homo sapiens.<\/em><\/p>\n\n\n\n<p>Para&nbsp;<strong>Ariadna Vilalta<\/strong>&nbsp;(Girona, 1979), ciberpsic\u00f3loga experta en \u00e9tica de la digitalizaci\u00f3n e inteligencia artificial aplicada,&nbsp;<em>Downton Abbey<\/em>&nbsp;sirve como el mejor ejemplo de lo que est\u00e1 suponiendo esta inmersi\u00f3n sin vuelta atr\u00e1s en el marem\u00e1gnum digital. No s\u00f3lo es su serie favorita, sino el hilo conductor de&nbsp;<em>Una vida siempre en l\u00ednea<\/em>&nbsp;(Ediciones Destino), libro en el que desgrana esta relativamente nueva disciplina -la&nbsp;<strong>ciberpsicolog\u00eda<\/strong>&#8211; dedicada a estudiar el creciente impacto de la tecnolog\u00eda en la conducta humana.<\/p>\n\n\n\n<p>\u00abEstamos participando en el mayor experimento psicol\u00f3gico de la historia sin haber le\u00eddo las instrucciones\u00bb, explica Vilalta en su libro. \u00abUn experimento global, continuo, sin grupo de control, en el que ni\u00f1os, adolescentes, adultos y personas mayores somos, al mismo tiempo, usuarios y cuerpos de ensayo. Y lo hacemos en versi\u00f3n beta permanente: todo cambia demasiado r\u00e1pido como para detenernos a comprender qu\u00e9 nos est\u00e1 pasando\u00bb.<\/p>\n\n\n\n<p class=\"has-ast-global-color-4-background-color has-background\">Para saber m\u00e1s<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e01-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2026\/07\/09\/17836146938323.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Salud.&nbsp;<a href=\"https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2026\/07\/09\/6a4bdcd2fc6c83035e8b4589.html\">El psiquiatra que lo sabe todo de la ansiedad y depresi\u00f3n de los j\u00f3venes: \u00abSu infelicidad no viene de las pantallas, sino de factores sociales mucho m\u00e1s grandes, como la vivienda o el trabajo\u00bb<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/e01-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2026\/05\/20\/17792886128947.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.elmundo.es\/papel\/lideres\/2026\/05\/20\/6a0dc3a8fc6c836a078b45c0.html\">El cient\u00edfico espa\u00f1ol que descubri\u00f3 11 nuevas enfermedades: \u00abAlgunas se camuflan bajo trastornos psiqui\u00e1tricos y son terribles\u00bb<\/a><\/p>\n\n\n\n<p>Adicci\u00f3n a internet o a los videojuegos, problemas de autoestima, FOMO, ansiedad social, telepressure&#8230; El listado de patolog\u00edas ligadas al ecosistema digital es casi tan infinito como el propio scroll de Instagram o TikTok. En persona, Vilalta convierte una entrevista en una conversaci\u00f3n llena de matices, pero es rotunda al afirmar que \u00absi fumas, puedes tener c\u00e1ncer de pulm\u00f3n y la nicotina es lo que te engancha, pero en el fondo t\u00fa decides si fumas o no. Por eso, creo que es importante que conozcamos&nbsp;<strong>qu\u00e9 nos puede pasar ante el exceso o abuso de todo lo que implica estar conectados<\/strong>\u00bb.<\/p>\n\n\n\n<p>Si a los adultos nos est\u00e1 costando encontrar el equilibrio a la hora de relacionarnos con las pantallas, en ni\u00f1os y adolescentes ese v\u00ednculo es especialmente problem\u00e1tico. \u00abEs muy importante que se saquen las pantallas de las habitaciones porque, como padre, t\u00fa tienes que saber qu\u00e9 est\u00e1n viendo tus hijos, con qui\u00e9n est\u00e1n hablando y en qu\u00e9 se est\u00e1n metiendo\u00bb, reclama Vilalta.<\/p>\n\n\n\n<p>En cuanto a los adultos, lo m\u00e1s habitual es encontrarse con esa sensaci\u00f3n de haber perdido la autonom\u00eda mental o emocional por culpa de la tecnolog\u00eda. La ciberpsic\u00f3loga insiste en que \u00abexisten herramientas, sobre todo si se es consciente de que has perdido algo que quieres recuperar. Es un primer paso fundamental. A todos nos cuesta cambiar los h\u00e1bitos y tenemos tendencia a recaer pero, al final, cuando te das cuenta de que te&nbsp;<strong>aporta m\u00e1s hacer otras cosas que entrar en bucles que son perjudiciales<\/strong>, merece la pena el esfuerzo\u00bb.<\/p>\n\n\n\n<p>No hay atajos, ni soluciones infalibles a corto plazo frente a problemas como los que genera la pornograf\u00eda online, por ejemplo, sino terapias personalizadas para una completa y efectiva&nbsp;<strong>desintoxicaci\u00f3n digital<\/strong>. \u00abEs necesario escuchar el s\u00edntoma no como patolog\u00eda aislada, sino como respuesta adaptativa a un entorno que sobreestimula, pero no acompa\u00f1a\u00bb, propone la ciberpsic\u00f3loga.<\/p>\n\n\n\n<p>Por las p\u00e1ginas del libro desfilan todo tipo de expertos, desde la pionera de la disciplina, Mary Aiken, hasta Steven Pinker o Jean Twenge, pero tambi\u00e9n experiencias personales de la propia Vilalta y casos cl\u00ednicos como el de Nuria, una mujer de 22 a\u00f1os que consultaba el m\u00f3vil cada cinco minutos y aseguraba:&nbsp;<strong>\u00abSi no me hablan, siento que no existo\u00bb<\/strong>. El conjunto sirve a la autora para ofrecer una serie de consejos y recursos muy \u00fatiles para combatir el aislamiento y el agotamiento que genera esta hiperestimulaci\u00f3n digital.<\/p>\n\n\n\n<p>Sin embargo, frente a las prohibiciones y la demonizaci\u00f3n de la tecnolog\u00eda, Vilalta plantea la necesidad de \u00abimplantar una educaci\u00f3n digital desde ni\u00f1os. El problema es que, aunque quisi\u00e9ramos hacer algo as\u00ed ahora, ya estamos con la IA y no nos estamos preparando para todo lo que viene, como la neurotecnolog\u00eda\u00bb. Se refiere a los implantes cerebrales y a los gadgets que se conectan al sistema nervioso para registrar, analizar, modificar o simular su actividad. De&nbsp;<em>Downton Abbey<\/em>&nbsp;a&nbsp;<em>Black Mirror<\/em>&nbsp;sin pasar por la casilla de salida.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Con su libro, a Vilalta le gustar\u00eda \u00abque aquellos que construyen y dise\u00f1an la tecnolog\u00eda tuvieran en cuenta a profesionales como yo, que aportamos el conocimiento y estudio de la mente humana a la ecuaci\u00f3n. Dise\u00f1ar y crear m\u00e1quinas sin considerar su impacto en la mente humana puede ser positivo a nivel comercial, pero es muy arriesgado\u00bb.<\/p>\n\n\n\n<p>Su otra propuesta, como un mantra que deber\u00edamos repetirnos cuando amanecemos y nos acostamos atados a la pantalla del m\u00f3vil, es el equilibrio, el autoconocimiento y la necesidad imperiosa de&nbsp;<strong>descansar<\/strong>&nbsp;en el sentido m\u00e1s amplio y cl\u00ednico del t\u00e9rmino. \u00abCesar en el trabajo, reparar las fuerzas con la quietud\u00bb, reza el diccionario de la RAE, y eso en el mundo hiperconectado que habitamos se hace cada vez m\u00e1s dif\u00edcil. El camino para aprender a estar solos es sinuoso, viene a decir la ciberpsic\u00f3loga, pero merece la pena emprenderlo para recuperar lo que se nos escapa por las grietas del mundo digital.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.elmundo.es\/papel\/historias\/2026\/07\/13\/6a53a11be9cf4a344f8b4576.html\">https:\/\/www.elmundo.es\/papel\/historias\/2026\/07\/13\/6a53a11be9cf4a344f8b4576.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por su libro &#8216;Una vida siempre en l\u00ednea&#8217; desfilan expertos y casos cl\u00ednicos con los que ofrece recursos para combatir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[51164,51170,51166,51169,51165,51167],"class_list":["post-126427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-ciberpsicologa-ariadna-vilalta","tag-desintoxicacion-digital","tag-experimento-psicologico","tag-hiperconexion-digital","tag-impacto-tecnologia","tag-libro-una-vida-siempre-en-linea"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=126427"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126427\/revisions"}],"predecessor-version":[{"id":126429,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126427\/revisions\/126429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/126428"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=126427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=126427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=126427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}