{"id":126421,"date":"2026-07-13T08:52:57","date_gmt":"2026-07-13T14:52:57","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=126421"},"modified":"2026-07-13T08:52:58","modified_gmt":"2026-07-13T14:52:58","slug":"goles-violaciones-e-impunidad-la-verguenza-de-un-mundial-de-futbol-impasible-ante-la-violencia-sexual-ods","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/goles-violaciones-e-impunidad-la-verguenza-de-un-mundial-de-futbol-impasible-ante-la-violencia-sexual-ods\/","title":{"rendered":"Goles, violaciones e impunidad: la verg\u00fcenza de un Mundial de f\u00fatbol impasible ante la violencia sexual | ODS"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-light-green-cyan-background-color has-background has-medium-font-size\">Las redes sociales se han incendiado por la presencia de futbolistas en la competici\u00f3n acusados o que enfrentan cargos por delitos sexuales.<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/11312797-1024x576.jpg\" alt=\"\" class=\"wp-image-126422\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/11312797-1024x576.jpg 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/11312797-300x169.jpg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/11312797-768x432.jpg 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/11312797-1536x864.jpg 1536w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/11312797.jpg 1706w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Achraf Hakimi es uno de los deportistas que disputa esta competici\u00f3n, aunque tiene una causa abierta en Francia por violaci\u00f3n.\u00a0Will Oliver\u00a0EFE<\/figcaption><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.elespanol.com\/autor\/ines-sanchez-manjavacas-castano\/?utm_cmp_rs=authorpage\">In\u00e9s S\u00e1nchez-Manjavacas Casta\u00f1o<\/a> \/ Enclave ODS<\/strong><\/p>\n\n\n\n<p id=\"paragraph_1\">Los focos est\u00e1n puestos sobre&nbsp;<a href=\"https:\/\/www.elespanol.com\/enclave-ods\/historias\/20260611\/temperaturas-extremas-rendimiento-amenaza-cambio-climatico-cierne-mundial-futbol\/1003744281505_0.html?utm_cmp_rs=linksinline\">el Mundial de F\u00fatbol&nbsp;<\/a>y sobre sus jugadores. El evento es&nbsp;<strong>el mayor escaparate deportivo<\/strong>, un gran hito para quienes integran las selecciones nacionales, y hay quien piensa que no todos deber\u00edan estar ah\u00ed.<\/p>\n\n\n\n<p id=\"paragraph_2\">Las redes sociales&nbsp;<strong>se han incendiado recientemente&nbsp;<\/strong>por la presencia y participaci\u00f3n de deportistas que han sido acusados o enfrentan cargos por delitos sexuales graves.<\/p>\n\n\n\n<p>Opini\u00f3n de la creadora de contenido Aitanaful sobre el Motorbeach de Vinuesa (Soria)<\/p>\n\n\n\n<p id=\"paragraph_3\">Hablamos de hombres muy j\u00f3venes que tienen&nbsp;<strong>millones de admiradores&nbsp;<\/strong>alab\u00e1ndoles en internet, comprando sus camisetas y siguiendo su ejemplo, dicen preocupadas desde la Federaci\u00f3n de Mujeres J\u00f3venes.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.elespanol.com\/enclave-ods\/historias\/20260619\/mundial-futbol-derechos-duda-averguenza-opinion-publica-fifa-preferido-mirar-lado\/1003744291680_0.html?utm_cmp_rs=relatednewsinline\">Un mundial de f\u00fatbol con los derechos en duda averg\u00fcenza a la opini\u00f3n p\u00fablica: \u00ab[La FIFA] Ha preferido mirar hacia otro lado\u00bb<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Los futbolistas acusados<\/h3>\n\n\n\n<p id=\"paragraph_4\">Uno de ellos es Thomas Partey, que\u00a0<a href=\"https:\/\/www.elespanol.com\/deportes\/futbol\/20250704\/thomas-partey-exjugador-arsenal-atletico-madrid-acusado-violacion-agresion-sexual\/1003743834659_0.html?utm_cmp_rs=linksinline\">enfrenta un proceso<\/a>\u00a0en el Reino Unido por<strong>\u00a0siete cargos de violaci\u00f3n\u00a0<\/strong>y uno de agresi\u00f3n sexual relacionados con cuatro denunciantes diferentes.<a href=\"https:\/\/www.outbrain.com\/what-is\/default\/es\"><\/a><\/p>\n\n\n\n<p id=\"paragraph_5\"><a href=\"https:\/\/www.elespanol.com\/deportes\/futbol\/20260619\/justicia-francesa-confirma-hakimi-juzgado-presunta-violacion\/1003744292107_0.html?utm_cmp_rs=linksinline\">Achraf Hakimi&nbsp;<\/a>es otro de los se\u00f1alados. El integrante del combinado marroqu\u00ed, y defensa del Paris Saint-Germain, ser\u00e1 juzgado en Francia&nbsp;<strong>acusado de violar a una joven de 24 a\u00f1os<\/strong>&nbsp;en 2023.<\/p>\n\n\n\n<p id=\"paragraph_6\">En la selecci\u00f3n de Cabo Verde \u2013una de las sorpresas de esta competici\u00f3n\u2013 se ha puesto el foco en su capit\u00e1n Ryan Mendes. Est\u00e1 siendo investigado en Nueva Zelanda por&nbsp;<strong>una presunta violaci\u00f3n<\/strong>&nbsp;durante un torneo el pasado marzo. Su v\u00edctima ser\u00eda una int\u00e9rprete brasile\u00f1a que trabajaba para la FIFA.<\/p>\n\n\n\n<p id=\"paragraph_7\">Cierran la lista Kaish\u016b Sano y Junya Ito, ambos del equipo japon\u00e9s. El primero fue detenido hace dos a\u00f1os por&nbsp;<strong>una agresi\u00f3n sexual grupal<\/strong>, aunque fue posteriormente liberado y la prensa de su pa\u00eds afirm\u00f3 que el caso se cerr\u00f3 con un acuerdo extrajudicial.<\/p>\n\n\n\n<p id=\"paragraph_8\">Entonces, el jugador&nbsp;<strong>ofreci\u00f3 disculpas p\u00fablicas a la v\u00edctima<\/strong>, aunque no fue condenado por la v\u00eda penal.<\/p>\n\n\n\n<p id=\"paragraph_9\">Al segundo tambi\u00e9n se le investig\u00f3 por agresi\u00f3n sexual en 2024, aunque neg\u00f3 las acusaciones y&nbsp;<strong>lleg\u00f3 a demandar a la denunciante<\/strong>. Finalmente, el caso se desestim\u00f3 por falta de pruebas. Estos son los m\u00e1s recientes, pero no se pueden olvidar otros nombres que estuvieron antes en el foco.<\/p>\n\n\n\n<p id=\"paragraph_10\">Por ejemplo, el de Neymar Jr,&nbsp;<strong>acusado en 2019 de violar a una modelo brasile\u00f1a<\/strong>, o el de Cristiano Ronaldo. El portugu\u00e9s fue denunciado en 2018 en Estados Unidos por cometer el mismo delito con una exmodelo una d\u00e9cada antes. En este caso tambi\u00e9n se acab\u00f3 desestimando la denuncia.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.elespanol.com\/enclave-ods\/historias\/20241125\/asesinadas-esclavizadas-mutiladas-vergonzoso-mapa-violencia-mujeres-mundo\/903160057_0.html?utm_cmp_rs=relatednewsinline\">Asesinadas, esclavizadas y mutiladas: este es el vergonzoso mapa de la violencia contra las mujeres en el mundo<\/a><\/p>\n\n\n\n<p id=\"paragraph_11\">A pesar de un se\u00f1alamiento tan serio,&nbsp;<strong>ninguno ha recibido ning\u00fan tipo de consecuencia<\/strong>&nbsp;en el \u00e1mbito deportivo, penal o social.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La decisi\u00f3n de Canad\u00e1<\/h3>\n\n\n\n<p id=\"paragraph_12\">El \u00fanico que se ha acercado a ello \u2013y ha supuesto un gran revuelo en la competici\u00f3n\u2013 ha sido Partey. El gan\u00e9s se perdi\u00f3 el partido inaugural de su selecci\u00f3n porque&nbsp;<a href=\"https:\/\/www.elespanol.com\/deportes\/futbol\/mundial\/20260612\/canada-niega-visado-thomas-partey-jugador-perdera-primer-partido-ghana-mundial\/1003744284583_0.html?utm_cmp_rs=linksinline\">Canad\u00e1 le deneg\u00f3 la entrada al pa\u00eds<\/a>&nbsp;por el proceso al que se enfrenta en Reino Unido.<\/p>\n\n\n\n<p id=\"paragraph_13\">Para Carla Vallejo, integrante de la coordinadora de la Asociaci\u00f3n de Mujeres Juezas de Espa\u00f1a (AMJE), se trata de una decisi\u00f3n que traslada \u00ab<strong>un mensaje coherente<\/strong>, con una pol\u00edtica p\u00fablica de apoyo y de protecci\u00f3n a las v\u00edctimas y de rechazo a la violencia sexual\u00bb.<\/p>\n\n\n\n<p id=\"paragraph_14\">Supone el reconocimiento de que la lucha contra esta lacra y el machismo&nbsp;<strong>concierne a toda la sociedad&nbsp;<\/strong>y no solo a la justicia y la polic\u00eda.<\/p>\n\n\n\n<p id=\"paragraph_15\">No obstante, Alberto Palomar, abogado y profesor de la universidad Carlos III de Madrid descarta que el veto del pa\u00eds norteamericano obligue a la FIFA&nbsp;<strong>a endurecer sus filtros globales.<\/strong><\/p>\n\n\n\n<p id=\"paragraph_16\">Algo que se debe a que las federaciones internacionales \u00ab<strong>viven m\u00e1s c\u00f3modas delegando en las autoridades de inmigraci\u00f3n<\/strong>&nbsp;y asumiendo luego las consecuencias\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Presunci\u00f3n de inocencia<\/h3>\n\n\n\n<p id=\"paragraph_17\">Una decisi\u00f3n as\u00ed, no es lo habitual. De hecho, hasta el momento,&nbsp;<strong>es la mayor consecuencia que ha vivido Partey.<\/strong><\/p>\n\n\n\n<p id=\"paragraph_18\">Normalmente, cuando los futbolistas reciben una denuncia de este tipo&nbsp;<strong>nada cambia realmente en sus vidas.<\/strong>&nbsp;Siguen jugando con sus respectivos clubes y participando en torneos internacionales.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.elespanol.com\/enclave-ods\/historias\/20221206\/oscuro-alineacion-indebida-mundial-qatar-trabajadores-inmigrantes\/662434155_0.html?utm_cmp_rs=relatednewsinline\">El lado oscuro del f\u00fatbol: la alineaci\u00f3n indebida del Mundial de Qatar con los trabajadores inmigrantes<\/a><\/p>\n\n\n\n<p id=\"paragraph_19\">La FIFA y los propios equipos se basan en&nbsp;<strong>la presunci\u00f3n de inocencia&nbsp;<\/strong>y en la inexistencia de una sentencia condenatoria.<\/p>\n\n\n\n<p id=\"paragraph_20\">La explicaci\u00f3n es sencilla: el organismo mundial&nbsp;<strong>rechaza convertirse en un tribunal penal global<\/strong>, cuentan los abogados Toni Roca y Abel Guntin, del&nbsp;<a href=\"https:\/\/www.himnus.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">despacho Himnus<\/a>, especializado en f\u00fatbol .<\/p>\n\n\n\n<p id=\"paragraph_21\">Adoptar medidas cautelares \u00able exigir\u00eda<strong>&nbsp;valorar judicialmente hechos no probados<\/strong>, vulnerando la presunci\u00f3n de inocencia y el derecho al trabajo de los atletas\u00bb, apuntan. Asimismo, la heterogeneidad en los procesos penales a nivel internacional&nbsp;<strong>imposibilita redactar una norma global neutra<\/strong>.<\/p>\n\n\n\n<p id=\"paragraph_22\">Al no existir homogeneidad jur\u00eddica entre pa\u00edses, cualquier protocolo interno de suspensi\u00f3n&nbsp;<strong>podr\u00eda resultar arbitrario, ineficaz o generar consecuencias radicalmente dispares&nbsp;<\/strong>seg\u00fan el territorio donde se tramite la investigaci\u00f3n.<\/p>\n\n\n\n<p id=\"paragraph_23\">Por su parte, apartar preventivamente a un jugador sin una base contractual bien clara expone a los clubes a<strong>&nbsp;reclamaciones econ\u00f3micas millonarias.&nbsp;<\/strong>Ante el temor a demandas, p\u00e9rdida de valor de mercado o da\u00f1o reputacional, las entidades suelen evitar las sanciones unilaterales.<\/p>\n\n\n\n<p id=\"paragraph_24\">Es decir, como mucho, llegan a la&nbsp;<strong>salida pactada del jugador<\/strong>, renegociaciones o a apartarlos de forma consensuada entre ambas partes.<\/p>\n\n\n\n<p id=\"paragraph_25\">Para el abogado Alberto Palomar, profesor de la universidad Carlos III de Madrid, que la FIFA evite suspender cautelarmente a futbolistas imputados responde a&nbsp;<strong>un conflicto competencial.<\/strong><\/p>\n\n\n\n<p id=\"paragraph_26\">\u00abAdoptar una medida provisional en un asunto como este&nbsp;<strong>puede afectar a las competencias de los jueces<\/strong>\u00ab, afirma el experto en derecho deportivo. Mientras los canales ordinarios no ordenen lo contrario, el organismo opta por evitar interferencias en el proceso penal.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.elespanol.com\/enclave-ods\/noticias\/20240624\/menores-sufrido-episodios-violencia-sexual-ambito-digital\/865413740_0.html?utm_cmp_rs=relatednewsinline\">Tres de cada cuatro menores han sufrido episodios de violencia sexual en el \u00e1mbito digital<\/a><\/p>\n\n\n\n<p id=\"paragraph_27\">Por su parte, Vallejo, de la&nbsp;<a href=\"https:\/\/www.mujeresjuezas.es\/\" rel=\"noreferrer noopener\" target=\"_blank\">AMJE<\/a>, recuerda que la presunci\u00f3n de inocencia no es \u00abuna patente de corso que impida o paralice cualquier acci\u00f3n o reclamaci\u00f3n social o de otras instituciones<strong>&nbsp;para proteger y defender a las v\u00edctimas&nbsp;<\/strong>y para exteriorizar el rechazo\u00bb.<\/p>\n\n\n\n<p id=\"paragraph_28\">Al contrario, opera dentro de los juzgados en el \u00e1mbito penal, pero fuera de ese entorno pueden y deben llevarse a cabo pol\u00edticas de buenas pr\u00e1cticas y&nbsp;<strong>exigencias de responsabilidad&nbsp;<\/strong>porque \u00abno todo lo que no se condene como delito es \u00e9tica o socialmente aceptable\u00bb, a\u00f1ade la magistrada.<\/p>\n\n\n\n<p id=\"paragraph_29\">La justicia solo puede acordar las medidas cautelares que prev\u00e9 la ley&nbsp;<strong>entre las que no est\u00e1 la suspensi\u00f3n profesional<\/strong>, expone. Esto pueden hacerlo los empleadores o instituciones responsables de un evento como el mundial.<\/p>\n\n\n\n<p id=\"paragraph_30\">\u00abNo hacerlo escud\u00e1ndose en la presunci\u00f3n de inocencia es&nbsp;<strong>confundir deliberadamente los \u00e1mbitos de competencia y responsabilidad&nbsp;<\/strong>que tiene cada organizaci\u00f3n\u00bb, manifiesta firme Vallejo.<\/p>\n\n\n\n<p id=\"paragraph_31\">En cuanto al escudo \u00e9tico de las entidades, Palomar aclara que los reglamentos internos s\u00ed \u00abpueden tener<strong>&nbsp;un plus de exigencia \u00e9tica<\/strong>\u00bb contractualmente aceptado, sin vulnerar la presunci\u00f3n de inocencia.<\/p>\n\n\n\n<p id=\"paragraph_32\">Esto ya se ve en otros deportes, como en las ligas estadounidenses de f\u00fatbol americano y de baloncesto. Ah\u00ed existen<strong>&nbsp;las cl\u00e1usulas de moralidad<\/strong>, que permiten apartar o rescindir el contrato a un jugador de forma inmediata si se ve envuelto en un esc\u00e1ndalo penal que da\u00f1e la reputaci\u00f3n de la entidad.<\/p>\n\n\n\n<p id=\"paragraph_33\">La diferencia es que estas competiciones est\u00e1n respaldadas por convenios colectivos centralizados que penalizan comportamientos sin condena penal firme, el f\u00fatbol europeo est\u00e1 fragmentado. Esta dispersi\u00f3n normativa&nbsp;<strong>dificulta ejecutar cl\u00e1usulas de moralidad unilateralmente<\/strong>, ya que chocan de inmediato con los derechos laborales b\u00e1sicos del deportista, exponen los abogados de Himnus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Errores del pasado<\/h3>\n\n\n\n<p id=\"paragraph_34\">Muchas veces, los propios equipos y los aficionados&nbsp;<strong>escudan al jugador acusado tild\u00e1ndolo de errores del pasado,<\/strong>&nbsp;pues las denuncias suelen llegar a\u00f1os despu\u00e9s de los hechos. \u00ab[Lo dicen] como quien pint\u00f3 un grafiti o hizo una gamberrada en el instituto con sus amigos\u00bb, exponen desde la&nbsp;<a href=\"https:\/\/mujeresjovenes.org\/\" rel=\"noreferrer noopener\" target=\"_blank\">Federaci\u00f3n de Mujeres J\u00f3venes.<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.elespanol.com\/enclave-ods\/referentes\/20260705\/ibhais-paso-anos-carcel-no-ocultar-muertes-catar-obedecia-condenaban-muerte\/1003744307158_0.html?utm_cmp_rs=relatednewsinline\">Ibhais pas\u00f3 3 a\u00f1os en la c\u00e1rcel por no ocultar las muertes de Catar 2022: \u00abSi no obedec\u00eda, me condenaban a muerte\u00bb<\/a><\/p>\n\n\n\n<p id=\"paragraph_35\">No se trata, aseguran, de un error. Especialmente cuando la mayor parte de los casos que conocemos hoy en d\u00eda&nbsp;<strong>se han producido cuando estos deportistas ya est\u00e1n en niveles altos de competici\u00f3n&nbsp;<\/strong>o, incluso, \u00abhan utilizado su posici\u00f3n de famoso o privilegiado para poder abusar de sus v\u00edctimas\u00bb.<\/p>\n\n\n\n<p id=\"paragraph_36\">Desde esta federaci\u00f3n entienden tambi\u00e9n que para la gran parte de la audiencia masculina&nbsp;<strong>estas acusaciones pasan completamente desapercibidas&nbsp;<\/strong>porque, al igual que los clubes, \u00ablo maquillan todo\u00bb con excusas como que el susodicho no estaba en un buen momento de su carrera, que la v\u00edctima se lo ha buscado o quer\u00eda hacerse famosa.<\/p>\n\n\n\n<p id=\"paragraph_37\">Tambi\u00e9n les preocupa&nbsp;<strong>el ejemplo que supone para los admiradores de los deportistas<\/strong>. Si alguien a quien consideran su \u00eddolo ha cometido un delito de \u00edndole sexual o est\u00e1 siendo juzgado por ello sin ning\u00fan tipo de consecuencia, \u00ab\u00bfqu\u00e9 le va a pasar a un chico normal y corriente?\u00bb.<\/p>\n\n\n\n<p id=\"paragraph_38\">Si ellos lo hacen, es porque puede hacerse, sentencian. Al final, estos jugadores&nbsp;<strong>\u00abson el espejo en el que millones de j\u00f3venes se ven reflejados\u00bb<\/strong>. Por eso, cuando ven este tipo de casos y la impunidad del agresor, tambi\u00e9n se refuerza y se justifica a\u00fan m\u00e1s la cultura de la violaci\u00f3n.<\/p>\n\n\n\n<p id=\"paragraph_39\">La situaci\u00f3n est\u00e1 tan aceptada, que en el partido del mundial entre Ghana e Inglaterra se produjo una pol\u00e9mica cuando Djed Spence, lateral brit\u00e1nico,&nbsp;<strong>se neg\u00f3 a darle la mano a Partey<\/strong>&nbsp;por la causa que tiene abierta.<\/p>\n\n\n\n<p id=\"paragraph_40\">La Federaci\u00f3n de Mujeres J\u00f3venes resalta que, en vez de aplaudir esta decisi\u00f3n,&nbsp;<strong>varios compa\u00f1eros salieron en defensa del gan\u00e9s<\/strong>&nbsp;e, incluso, el propio acusado escribi\u00f3 un comunicado sobre la acci\u00f3n.<\/p>\n\n\n\n<p id=\"paragraph_41\">Lo ocurrido solo demuestra que<strong>&nbsp;se protegen entre ellos<\/strong>&nbsp;y cuando hay una voz disidente, enseguida se critica y se llama al orden, se quejan desde la organizaci\u00f3n feminista. \u00abQuiz\u00e1s necesitamos m\u00e1s referentes como Spence y menos como Thomas Partey, Ra\u00fal Asencio y sobre todo, menos \u00eddolos como Dani Alves [los dos \u00faltimos juzgados por delitos sexuales]\u00bb.<\/p>\n\n\n\n<p id=\"paragraph_42\">Vallejo, de la AMJE, lamenta que toda esta situaci\u00f3n demuestra que, actualmente, \u00ab<strong>no existe un verdadero compromiso<\/strong>&nbsp;de lucha contra la violencia en espacios que son tremendamente androc\u00e9ntricos y machistas\u00bb. \u00c1mbitos en los que el&nbsp;<a href=\"https:\/\/www.elespanol.com\/enclave-ods\/historias\/20260308\/feminismo-pierde-apoyo-jovenes-solo-hombres-cree-existe-gran-desigualdad-genero\/1003744158585_0.html?utm_cmp_rs=linksinline\">discurso feminista&nbsp;<\/a>y de respeto a las mujeres no ha calado.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.elespanol.com\/enclave-ods\/historias\/20260713\/goles-violaciones-impunidad-verguenza-mundial-futbol-impasible-violencia-sexual\/1003744316830_0.html\">https:\/\/www.elespanol.com\/enclave-ods\/historias\/20260713\/goles-violaciones-impunidad-verguenza-mundial-futbol-impasible-violencia-sexual\/1003744316830_0.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las redes sociales se han incendiado por la presencia de futbolistas en la competici\u00f3n acusados o que enfrentan cargos por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126422,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[2743,51162,51160,51161,51159],"class_list":["post-126421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-abusos-sexuales","tag-achraf-hakimi","tag-discurso-feminista","tag-impunidad-futbolistas-mundial-2026","tag-mundial-futbol"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=126421"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126421\/revisions"}],"predecessor-version":[{"id":126423,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126421\/revisions\/126423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/126422"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=126421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=126421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=126421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}