{"id":126327,"date":"2026-07-11T18:11:53","date_gmt":"2026-07-12T00:11:53","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=126327"},"modified":"2026-07-11T18:11:55","modified_gmt":"2026-07-12T00:11:55","slug":"el-inah-reporta-3-716-piezas-arqueologicas-repatriadas-en-lo-que-va-del-sexenio-de-sheinbaum-el-pais","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/el-inah-reporta-3-716-piezas-arqueologicas-repatriadas-en-lo-que-va-del-sexenio-de-sheinbaum-el-pais\/","title":{"rendered":"El INAH reporta 3.716 piezas arqueol\u00f3gicas repatriadas en lo que va del sexenio de Sheinbaum | El Pa\u00eds"},"content":{"rendered":"\n<p>La mayor\u00eda de los objetos recuperados se encontraban en Estados Unidos, Canad\u00e1 e Italia<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/PiezasRecuperadas-1024x684.png\" alt=\"\" class=\"wp-image-126328\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/PiezasRecuperadas-1024x684.png 1024w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/PiezasRecuperadas-300x200.png 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/PiezasRecuperadas-768x513.png 768w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/07\/PiezasRecuperadas.png 1190w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Piezas arqueol\u00f3gicas devueltas a M\u00e9xico, de los estados de Tennessee y Washington, en Estados Unidos. M\u00f3nica Gonz\u00e1lez Islas<\/figcaption><\/figure>\n\n\n\n<p>Sara Gonz\u00e1lez \/ El Pa\u00eds<\/p>\n\n\n\n<p>El Instituto Nacional de Antropolog\u00eda e Historia (INAH) ha presentado\u00a0un balance de las piezas arqueol\u00f3gicas que han sido recuperadas\u00a0en lo que va del sexenio de la presidenta\u00a0Claudia Sheinbaum. En la conferencia matutina de este viernes, el director del organismo, Joel Omar V\u00e1zquez, ha informado que desde octubre de 2024 hasta la fecha se han repatriado un total de 3.716 objetos de importante valor hist\u00f3rico y cultural para el pa\u00eds.<\/p>\n\n\n\n<p>En su mayor\u00eda,\u00a0los objetos se encontraban en Estados Unidos, desde donde fueron repatriadas 3.369 piezas. Le sigue Italia, con la devoluci\u00f3n de 174; Canad\u00e1, que regres\u00f3 otras 133; Francia, con 19, y Espa\u00f1a, con siete. \u201cHay una recuperaci\u00f3n de patrimonio hist\u00f3rico y arqueol\u00f3gico que\u00a0se ha estado dando a trav\u00e9s del di\u00e1logo diplom\u00e1tico\u00a0en diferentes pa\u00edses del mundo y vamos a seguir, por instrucciones de la presidenta, con este esfuerzo y determinaci\u00f3n para recuperar la memoria, la identidad, y la pertenencia de los pueblos antiguos\u201d, mencion\u00f3 V\u00e1zquez.<\/p>\n\n\n\n<p>El director del INAH asegur\u00f3 que las piezas recuperadas por la actual Administraci\u00f3n ya representan una cifra 10 veces mayor que la registrada durante el sexenio de Enrique Pe\u00f1a Nieto. Como referencia, indic\u00f3 que entre 2006 y 2012, durante el Gobierno de Felipe Calder\u00f3n, se recuperaron 5.479 bienes culturales; entre 2012 y 2018, en el mandato de Pe\u00f1a Nieto, fueron 351; mientras que en el sexenio de Andr\u00e9s Manuel L\u00f3pez Obrador se repatriaron 14.162 objetos.<\/p>\n\n\n\n<p>Entre los objetos repatriados m\u00e1s valiosos destaca un cr\u00e1neo humano masculino recubierto con teselas de turquesa, perteneciente a la cultura mixteca y originario de la regi\u00f3n que hoy abarcan los Estados de Oaxaca y Puebla. La pieza, que se exhib\u00eda en el Museo de Etnolog\u00eda de Leiden, en Pa\u00edses Bajos, tambi\u00e9n presenta incrustaciones de concha, jade\u00edta y cuarzo. Tras su repatriaci\u00f3n, el cr\u00e1neo ya se encuentra en exhibici\u00f3n en la Villa de Tututepec, en la Costa de Oaxaca.<\/p>\n\n\n\n<p>Otra de las piezas es un panel labrado de la\u00a0cultura maya, correspondiente al periodo Cl\u00e1sico Tard\u00edo (600-900 d. C.) y procedente de Chiapas. El relieve representa a P\u00e1jaro Jaguar, gobernante de la antigua ciudad de Yaxchil\u00e1n, y fue recuperado en Nueva York antes de ser repatriado a M\u00e9xico. \u201cEs un monumento con un alto valor epigr\u00e1fico, integrado por 24 bloques de glifos en donde podemos observar una escena con funci\u00f3n pol\u00edtica y propagand\u00edstica destinada a legitimar v\u00ednculos de subordinaci\u00f3n y poder\u201d, explic\u00f3 V\u00e1zquez. Tambi\u00e9n en Nueva York se recuper\u00f3 una escultura antropomorfa originaria de las culturas del Altiplano Central. Elaborada en roca bas\u00e1ltica con t\u00e9cnicas de talla en bajorrelieve, la pieza conserva vestigios de pigmento rojo y representa a un personaje adulto.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/elpais.com\/mexico\/2026-07-10\/el-inah-reporta-3716-piezas-arqueologicas-repatriadas-en-lo-que-va-del-sexenio-de-sheinbaum.html\" target=\"_blank\" rel=\"noreferrer noopener\">El Pa\u00eds<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de los objetos recuperados se encontraban en Estados Unidos, Canad\u00e1 e Italia<\/p>\n","protected":false},"author":1,"featured_media":126328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[4686,1505,4025,4482,1037,6320,46678,51109],"class_list":["post-126327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-canada","tag-claudia-sheinbaum","tag-estados-unidos","tag-francia","tag-inah","tag-italia","tag-piezas-arqueologicas","tag-repatriadas"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=126327"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126327\/revisions"}],"predecessor-version":[{"id":126329,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/126327\/revisions\/126329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/126328"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=126327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=126327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=126327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}