{"id":123229,"date":"2026-05-29T07:55:21","date_gmt":"2026-05-29T13:55:21","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=123229"},"modified":"2026-05-29T07:55:22","modified_gmt":"2026-05-29T13:55:22","slug":"opinion-cronica-de-otro-festejo-de-los-90-anos-de-manuel-bartlett","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/opinion-cronica-de-otro-festejo-de-los-90-anos-de-manuel-bartlett\/","title":{"rendered":"Opini\u00f3n | Cr\u00f3nica de otro festejo de los 90 a\u00f1os de Manuel Bartlett"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">*Estuvieron presentes ex diputados y ex Presidentes Municipales<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"972\" height=\"574\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/05\/MANUEL-BARTLETT-EN-PUEBLA.jpg\" alt=\"\" class=\"wp-image-123230\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/05\/MANUEL-BARTLETT-EN-PUEBLA.jpg 972w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/05\/MANUEL-BARTLETT-EN-PUEBLA-300x177.jpg 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2026\/05\/MANUEL-BARTLETT-EN-PUEBLA-768x454.jpg 768w\" sizes=\"(max-width: 972px) 100vw, 972px\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-4865f9003ac6cfcf5a7f44570e7f0aa1\"><strong><em>Por Ra\u00fal Torres Salmer\u00f3n \/ Sin L\u00edmites<\/em><\/strong><\/p>\n\n\n\n<p>Don Manuel Bartlett D\u00edaz, cumpli\u00f3 90 a\u00f1os el 23 de febrero pasado. En Puebla, amigos y ex funcionarios de su Gobierno, lo festejaron el 28 de febrero en una residencia de La Carca\u00f1a en Cholula.<\/p>\n\n\n\n<p>Ahora el 23 de mayo, don Manuel acudi\u00f3 a Puebla a otro festejo, esta vez organizado por Wenceslao Herrera Coyac ex Diputado Local, quien fue dirigente campesino y por Edith Cid Palacios, ex Presidenta Municipal de Tepexi de Rodr\u00edguez.<\/p>\n\n\n\n<p>Fueron convocados algunos dirigentes, diputados y alcaldes de ese tiempo a comer en las instalaciones del Centro Internacional de Prospectiva y Altos Estudios (CIPAE), de la 3 poniente 711 en el Centro Hist\u00f3rico de Puebla, dirigido por don Luis Benavidez Ilizaliturri.<\/p>\n\n\n\n<p>Desde temprana hora, en una mesa en forma de U, se colocaron manteles, vasos, cubiertos y platos, as\u00ed como botanas de pepitas de calabaza. La cita fue a las 14 horas. El men\u00fa consisti\u00f3 en consom\u00e9 y barbacoa, tortillas, cemitas peque\u00f1as de pata, queso y milanesa; chicharr\u00f3n prensado, as\u00ed como pan de Zacatl\u00e1n, dulce de calabaza y pitaya. Las bebidas ofrecidas fueron agua de jamaica y pulque.<\/p>\n\n\n\n<p>Fue Wenceslao Herrera, quien hizo el ofrecimiento de la comida por los 90 a\u00f1os del festejado. Record\u00f3 los viajes en helic\u00f3ptero para llegar a recorrer hasta 5 municipios por d\u00eda. Don Manuel recorri\u00f3 5 veces el estado en su sexenio visitando los 217 municipios, que ning\u00fan gobernador hab\u00eda realizado con anterioridad.<\/p>\n\n\n\n<p>Hizo n\u00fameros y habl\u00f3 de cientos de horas de vuelo, cont\u00f3 an\u00e9cdotas como el desplome del helic\u00f3ptero segundos despu\u00e9s de despegar, donde no hubo da\u00f1os que lamentar, solo el susto de sus ocupantes.<\/p>\n\n\n\n<p>Ex funcionarios presentes recordaron que durante ese sexenio hubo dos accidentes. En mayo de 1993 en Iz\u00facar, tensiones pol\u00edticas provocadas por el proceso electoral municipal provocaron la ca\u00edda de un helic\u00f3ptero Eurocopter AS365 Dauphin, que estaba en periodo de pruebas por el Gobierno del Estado de Puebla.<\/p>\n\n\n\n<p>Luego de los hechos de Iz\u00facar, Carlos Salinas de Gortari, Presidente de la Rep\u00fablica entonces, envi\u00f3 al Gobierno de Puebla en pr\u00e9stamo, un helic\u00f3ptero Bell 412 que operaba la Comisi\u00f3n Federal de Electricidad. Luego de revisi\u00f3n y acondicionamiento en talleres especializados de Estados Unidos, meses despu\u00e9s, en visita al municipio de Tlacuilotepec, la nave a\u00e9rea al ir a reabastecerse de combustible al aeropuerto de Poza Rica o del Taj\u00edn, como se le conoce, se desplom\u00f3 en un campo deportivo de Tihuatl\u00e1n, Veracruz, hubo varios muertos, incluido el Jefe de Giras, Miguel \u00c1ngel Ceballos.<\/p>\n\n\n\n<p>En el agradecimiento del convivio, don Manuel agradeci\u00f3 la invitaci\u00f3n y record\u00f3 su trabajo por Puebla, junto con los presentes. \u201cTrabajamos juntos por Puebla\u201d, extern\u00f3 y record\u00f3 que el trabajo fundamental de su gobierno fue en los rubros de educaci\u00f3n y salud.<\/p>\n\n\n\n<p>Refiri\u00f3 a manera de an\u00e9cdota que, por ley, se otorg\u00f3 a los municipios que a trav\u00e9s de juntas de vecinos y autoridades decidieran las obras importantes. Se instalaron los Comit\u00e9s de Planeaci\u00f3n para el Desarrollo Municipal (COPLADEMUN).<\/p>\n\n\n\n<p>Cuando un Gobernador visita un municipio, manifest\u00f3, siempre hay reclamaciones. \u201cEntonces, evit\u00e9 que me reclamaran, pues la queja era directa para los Presidentes Municipales a quienes el pueblo rega\u00f1aba y no a m\u00ed\u201d, expres\u00f3 sonriente.<\/p>\n\n\n\n<p>Despu\u00e9s de la comida, algunos invitados hicieron uso de la palabra, platicaron sobre el beneficio de sus municipios, cuestiones anecd\u00f3ticas, todo en ambiente de amistad y camarader\u00eda.<\/p>\n\n\n\n<p>Alguien coment\u00f3, pues la mayor\u00eda de los presentes eran de la tercera edad, lo que dijo entre sus amigos el ex Diputado Local y ex dirigente campesino, Sa\u00fal Coronel Aguirre, como f\u00f3rmula para mejorar la salud y enfrentar las vicisitudes de la edad: \u201cComer bien, dormir bien y dormir solito\u201d. Las risas estuvieron a la orden del d\u00eda.<\/p>\n\n\n\n<p>No faltaron las fotos del recuerdo y la del grupo. As\u00ed concluy\u00f3 el segundo festejo en Puebla de los 90 a\u00f1os de don Manuel Bartlett. Al final, Manuel Senderos ley\u00f3 el acr\u00f3stico y poema a don Manuel, escrito por don Luis Benavidez, que est\u00e1 al final de este escrito.<\/p>\n\n\n\n<p>Entre los asistentes quienes fueron ex legisladores y dirigentes estuvieron:<\/p>\n\n\n\n<p>Wenceslao Herrera Coyac, ex Diputado Local y su esposa Estela Miranda; Aurelio Mart\u00ednez \u00c1vila, ex Alcalde de Coyotepec; Ant\u00edoco Cortez Gregorio, ex Alcalde de Juan N. M\u00e9ndez; Zenorina Gonz\u00e1lez Ortega, ex Diputada Local y ex Alcaldesa de Xicotepec e Isabel Merlo Talavera, ex Alcaldesa de Huaquechula.<\/p>\n\n\n\n<p>Javier Molina Mora, ex Alcalde de Cuetzalan; Teresa Arriaga Mora, ex Alcaldesa de Ayotoxco de Guerrero; Leobardo Garc\u00eda Galloso, ex Alcalde de Tlacuilotepec; Manuel Bautista Ram\u00edrez, ex Alcalde de Jonotla; Joel Cuevas T\u00e9llez, los ex diputados locales Joel Cuevas T\u00e9llez, Jos\u00e9 Luis M\u00e1rquez Mart\u00ednez y Laura Alicia S\u00e1nchez Corro; Marlit Moreno \u00c1lvarez, ex Alcaldesa de Xochiapulco y V\u00edctor Manuel Rojas, ex Alcalde de Huehuetla.<\/p>\n\n\n\n<p>Los ex diputados locales Alberto Jim\u00e9nez Merino, H\u00e9ctor Ordu\u00f1a M\u00e1rquez, Silvia Elena del Valle y Balbuena, Sa\u00fal Coronel Aguirre, C\u00e1ndido Mota L\u00f3pez, Gudelia Tapia Vargas y Miguel \u00c1ngel Mart\u00ednez Escobar. Edith Cid Palacios, ex Alcaldesa de Tepexi de Rodr\u00edguez; las ex diputadas federales Marina Blanco Casco y Josefina Garc\u00eda Hern\u00e1ndez y&nbsp;&nbsp; &nbsp;Amalia Bonifacio Jacinto, ex Alcaldesa de Tlatlauquitepec.<\/p>\n\n\n\n<p>Otros invitados fueron Mardonio Carrillo R\u00edos, Beatriz Herrera L\u00f3pez, Magaly Herrera L\u00f3pez,&nbsp; Leticia Montagner, Juan L\u00f3pez Moreno, V\u00edctor Manuel Rojas, Sergio Ortega, Gabriel Miranda L\u00f3pez, Guadalupe Natalia Cid Palacios, Patricia Ortiz Moreno, Mar\u00eda Elena Medrano P\u00e9rez, Xanat Citlali Bautista y el luchador social de la Mixteca, Juan L\u00f3pez Moreno.<\/p>\n\n\n\n<p>Estuvieron presentes los ex funcionarios p\u00fablicos Carlos Meza Viveros, Secretario de Gobernaci\u00f3n; Manuel R. Villa Issa, Secretario de Desarrollo Rural; Ra\u00fal Torres Salmer\u00f3n, Director de Comunicaci\u00f3n Social; H\u00e9ctor Posadas Manzano, Secretario Auxiliar; Vicente Luna Patricio, Educaci\u00f3n para Adultos; Pedro de Jes\u00fas Salda\u00f1a, Jefe de Giras; Mois\u00e9s Hern\u00e1ndez Hern\u00e1ndez, Educaci\u00f3n Ind\u00edgena; Mauro Uscanga Villalobos, Subsecretario de Finanzas; Jos\u00e9 Fabi\u00e1n Sandoval, Secretario de Educaci\u00f3n y Pierre Gilly D\u00edaz, Director del DIF.<\/p>\n\n\n\n<p>Por el CIPAE estuvieron don Luis Benavidez Ilizaliturri; su esposa Irma Vaca Pacheco; Manuel Senderos Bracamonte; Marco Antonio Serrano T\u00e9llez; Remedios Carolina Qu\u00edo Velasco y Gerardo Paul Arvizu. &nbsp;<\/p>\n\n\n\n<p>En fin, como escribi\u00f3 Luis G. Benavides Ilizaliturri (M\u00e9xico, 1937), en su soneto y acr\u00f3stico Manuel Bartlett en sus 90 a\u00f1os:<\/p>\n\n\n\n<p><strong>M<\/strong>anuel, M\u00e9xico en tu sangre vibra<\/p>\n\n\n\n<p><strong>A<\/strong>sida a escudo de tenaz justicia<\/p>\n\n\n\n<p><strong>N<\/strong>acida de humanismo con pericia:<\/p>\n\n\n\n<p><strong>U<\/strong>n quehacer viviente que equilibra.<\/p>\n\n\n\n<p><strong>E<\/strong>l tiempo pasa y el vivir calibra<\/p>\n\n\n\n<p><strong>L<\/strong>ibar en veces penas de sevicia:<\/p>\n\n\n\n<p><strong>B<\/strong>atientes olas llenas de malicia<\/p>\n\n\n\n<p><strong>A<\/strong>rmando falsedades en palabra.<\/p>\n\n\n\n<p><strong>R<\/strong>evives la utop\u00eda en tus labores,<\/p>\n\n\n\n<p><strong>T<\/strong>raes futuro al presente, con sentido;<\/p>\n\n\n\n<p><strong>L<\/strong>ogros que, al hilarlos, son fulgores.<\/p>\n\n\n\n<p><strong>E<\/strong>n noventa a\u00f1os de esfuerzos superiores<\/p>\n\n\n\n<p><strong>T<\/strong>u quehacer por la Patria ha florecido;<\/p>\n\n\n\n<p><strong>T<\/strong>ienes \u00a1D\u00edaz! para afirmar honores.<\/p>\n\n\n\n<p>raultorress@hotmail.com<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>+ OPINI\u00d3N : Las opiniones expresadas son responsabilidad del autor<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Estuvieron presentes ex diputados y ex Presidentes Municipales Por Ra\u00fal Torres Salmer\u00f3n \/ Sin L\u00edmites Don Manuel Bartlett D\u00edaz, cumpli\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":123230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8,19],"tags":[274],"class_list":["post-123229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-limites-2","tag-manuel-bartlett"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/123229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=123229"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/123229\/revisions"}],"predecessor-version":[{"id":123231,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/123229\/revisions\/123231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/123230"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=123229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=123229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=123229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}