{"id":102212,"date":"2025-07-04T07:15:19","date_gmt":"2025-07-04T13:15:19","guid":{"rendered":"https:\/\/losperiodistas.com.mx\/portal\/?p=102212"},"modified":"2025-07-04T07:15:20","modified_gmt":"2025-07-04T13:15:20","slug":"el-endurecimiento-migratorio-en-ee-uu-eleva-el-negocio-del-trafico-de-personas-en-mexico-efe","status":"publish","type":"post","link":"https:\/\/losperiodistas.com.mx\/portal\/el-endurecimiento-migratorio-en-ee-uu-eleva-el-negocio-del-trafico-de-personas-en-mexico-efe\/","title":{"rendered":"El endurecimiento migratorio en EE.UU. eleva el negocio del tr\u00e1fico de personas en M\u00e9xico | EFE"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"540\" src=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2025\/07\/migrantes.webp\" alt=\"\" class=\"wp-image-102213\" srcset=\"https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2025\/07\/migrantes.webp 900w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2025\/07\/migrantes-300x180.webp 300w, https:\/\/losperiodistas.com.mx\/portal\/wp-content\/uploads\/2025\/07\/migrantes-768x461.webp 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"wp-element-caption\">Fotograf\u00eda de archivo de migrantes en fila en una estaci\u00f3n migratoria, en Tapachula (M\u00e9xico). EFE\/ Juan Manuel Blanco <\/figcaption><\/figure>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-23db7e95974579b190d8bc7ea9a6cef6\"><strong>Agencia EFE<\/strong><\/p>\n\n\n\n<p>Tapachula (M\u00e9xico) (EFE).- La cancelaci\u00f3n del programa CBP One y otras medidas contra la migraci\u00f3n irregular adoptadas por el presidente de EE.UU., Donald Trump, han tenido efectos en Tapachula, epicentro de la crisis migratoria en el sur de M\u00e9xico, donde los traficantes de personas pelean por la ruta hasta la frontera norte, seg\u00fan denunciaron este mi\u00e9rcoles activistas y migrantes.<\/p>\n\n\n\n<p>As\u00ed lo indic\u00f3 el director del Centro de Dignificaci\u00f3n Humana (CDH) en esa ciudad fronteriza, Luis Rey Garc\u00eda Villagr\u00e1n, quien subray\u00f3 que los traficantes de personas est\u00e1n cobrando entre 10.000 y 15.000 d\u00f3lares por viaje.<\/p>\n\n\n\n<p>\u201cPor eso, la lucha intestina tambi\u00e9n de los carteles, por eso, la guerra de la polic\u00eda chiapaneca (Chiapas) con los diferentes carteles porque la mitad de eso que se gana de ese bot\u00edn que tienen los traficantes de personas los carteles tienen que ver con esta guerra intestina porque se est\u00e1 peleando la ruta del tr\u00e1fico y trata de personas\u201d, inform\u00f3.<\/p>\n\n\n\n<p>De hecho, Garc\u00eda Villagr\u00e1n apunt\u00f3 que, en ocasiones, los migrantes son acercados al cruzar el r\u00edo Suchiate, que divide a M\u00e9xico con Guatemala, y desde all\u00ed son llevados hasta la frontera con Estados Unidos, situaci\u00f3n que refleja que la migraci\u00f3n irregular no se ha detenido pese a las pol\u00edticas de Washington.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-migracion-irregular-negocio-lucrativo\">Migraci\u00f3n irregular, negocio lucrativo<\/h2>\n\n\n\n<p>En la mayor ciudad fronteriza del sur de M\u00e9xico, se encuentra la migrante cubana Ghislayne Jim\u00e9nez Moret, quien narr\u00f3 a EFE que pag\u00f3 pasajes de 5.000 d\u00f3lares de su pa\u00eds hasta Nicaragua y de ese pa\u00eds fue trasladada a la frontera de M\u00e9xico con Guatemala por otros traficantes.<\/p>\n\n\n\n<p>&nbsp;\u00abClaro, nosotros nos venimos de manera ilegal, pagamos hasta Nicaragua, porque Cuba es una isla que est\u00e1 en medio del mar y no tiene frontera y luego pagamos pasajes de 5.000 d\u00f3lares cuando llegamos a Nicaragua hay gentes o \u2018coyotes\u2019, que nos traen hasta ac\u00e1 (Tapachula), y estos cobran en d\u00f3lares\u00bb, agreg\u00f3 Moret.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/efe.com\/wp-content\/uploads\/2025\/07\/asilo.webp?resize=900%2C600&amp;ssl=1\" alt=\"asilo Trump\" class=\"wp-image-1989756\"\/><figcaption class=\"wp-element-caption\">Fotograf\u00eda de archivo de migrantes en fila para solicitar asilo, en Tapachula (M\u00e9xico). EFE\/ Juan Manuel Blanco<\/figcaption><\/figure>\n\n\n\n<p>Esta migrante, de profesi\u00f3n psic\u00f3loga, cont\u00f3 que trabaja en una empacadora donde labora alrededor de 17 horas diarias y no pueden dejar de hacer las actividades porque tiene que cubrir sus gastos diarios.<\/p>\n\n\n\n<p>Por su parte, el ecuatoriano Fredy Lozano narr\u00f3 que lleg\u00f3 a Tapachula, la mayor ciudad fronteriza en el sure\u00f1o estado de Chiapas, hace un a\u00f1o y durante su traves\u00eda las diversas autoridades&nbsp;<a href=\"https:\/\/efe.com\/mundo\/2025-07-02\/cruce-inmigrantes-frontera-eeuu-mexico-cifras\/\">migratorias<\/a>&nbsp;le ped\u00edan dinero a cambio de dejarlos pasar porque no traen pasaporte o visa.<\/p>\n\n\n\n<p>\u201cEl permiso permanente para pasar por pa\u00eds, como nosotros no lo ten\u00edamos y mi familia es ecuatoriana ellos les cobraban m\u00e1s\u201d, indic\u00f3 Lozano, al se\u00f1alar que se encuentra de manera irregular limpiando vidrios de autom\u00f3viles, ya que est\u00e1 a la espera de sus documentos para poder salir de la frontera sur de manera legal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-limbo-para-los-migrantes\">Un limbo para los migrantes<\/h2>\n\n\n\n<p>La Administraci\u00f3n de&nbsp;<a href=\"https:\/\/efe.com\/espana\/2025-07-02\/menores-migrantes-acogida-supremo-gobierno-canarias\/\">Trump<\/a>&nbsp;ha eliminado una serie de programas y beneficios migratorios creados por su antecesor, entre ellos el parole humanitario para Cuba, Nicaragua, Venezuela y Hait\u00ed y la aplicaci\u00f3n CBP One, que permit\u00eda pedir cita para entrar de manera legal por la frontera.<\/p>\n\n\n\n<p>Como consecuencia, m\u00e1s de medio mill\u00f3n de personas se han quedado en un limbo legal -mientras los tribunales deciden sobre la legalidad de los programas- o directamente en una situaci\u00f3n migratoria irregular.<\/p>\n\n\n\n<p>Trump busca acelerar las deportaciones y detenciones para cumplir con su promesa de campa\u00f1a de expulsar a los m\u00e1s de 11 millones de migrantes indocumentados que viven en el pa\u00eds.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/efe.com\/mundo\/2025-07-04\/mexico-trafico-personas-medidas-migratorias-eeuu\/\">https:\/\/efe.com\/mundo\/2025-07-04\/mexico-trafico-personas-medidas-migratorias-eeuu\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agencia EFE Tapachula (M\u00e9xico) (EFE).- La cancelaci\u00f3n del programa CBP One y otras medidas contra la migraci\u00f3n irregular adoptadas por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":102213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[39781,39780],"class_list":["post-102212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-migrantes-a-ee-uu","tag-trafico-de-personas-mexico"],"_links":{"self":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/102212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=102212"}],"version-history":[{"count":1,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/102212\/revisions"}],"predecessor-version":[{"id":102214,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/posts\/102212\/revisions\/102214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media\/102213"}],"wp:attachment":[{"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=102212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=102212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losperiodistas.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=102212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}